{"id":18728,"date":"2020-07-01T17:34:08","date_gmt":"2020-07-01T15:34:08","guid":{"rendered":"https:\/\/www.valledeegues.com\/?p=18728"},"modified":"2020-07-01T17:34:08","modified_gmt":"2020-07-01T15:34:08","slug":"el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos","status":"publish","type":"post","link":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/","title":{"rendered":"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos"},"content":{"rendered":"<blockquote>\n<p class=\"p1\">Con una partida cercana a los 70.000 euros, el Consistorio apuesta por la digitalizaci\u00f3n y la conexi\u00f3n. Pretende dar respuesta as\u00ed a una reivindicaci\u00f3n hist\u00f3rica que se ha visto agravada estos \u00faltimos meses por el confinamiento ocasionado por el Covid-19<\/p>\n<\/blockquote>\n<p>Un Valle totalmente digital, y conectado al 100% en\u00a0el menor plazo posible. Bajo la premisa de este objetivo, el Ayuntamiento\u00a0del Valle de Eg\u00fc\u00e9s apuesta este verano por lograr la digitalizaci\u00f3n y\u00a0conexi\u00f3n total de los concejos de Badost\u00e1in, Elcano, Azpa, El\u00eda,\u00a0Sagaseta, Ardanaz e Ibiricu, as\u00ed como de los n\u00facleos de Eransus y\u00a0Ust\u00e1rroz. Y para ello convocar\u00e1 esta semana un concurso p\u00fablico para\u00a0licitar en ellos el despliegue de la red de fibra \u00f3ptica. Un proyecto que\u00a0contar\u00e1 con una partida cercana a los 70.000 euros.<\/p>\n<p>El Consistorio, de este modo, pretende atender y dar respuesta as\u00ed a una\u00a0reivindicaci\u00f3n hist\u00f3rica de sus concejos. Fuerte demanda estos \u00faltimos\u00a0a\u00f1os que, adem\u00e1s, se ha visto agravada desde el pasado mes de marzo\u00a0por el confinamiento ocasionado tras la pandemia del Covid-19.<\/p>\n<p>En este sentido, la alcaldesa del Valle de Eg\u00fc\u00e9s, Amaya Larraya, destaca\u00a0&#8220;el compromiso inequ\u00edvoco del equipo de gobierno con el desarrollo\u00a0tecnol\u00f3gico y la conectividad de todos los lugares del Valle\u201d: \u201cLa demanda\u00a0de acceso a servicios digitales es cada vez mayor, y todos los vecinos\u00a0deben hacerlo en condiciones de calidad\u201d. Por su parte, Jos\u00e9 Miguel\u00a0Bernal, concejal de Modernizaci\u00f3n de la Administraci\u00f3n, reafirma la\u00a0iniciativa como \u201cun paso m\u00e1s en la estrategia de desarrollo tecnol\u00f3gico en\u00a0todos los sectores\u201d. \u201cLa crisis del Covid-19 ha puesto de manifiesto la\u00a0necesidad de tener una conexi\u00f3n de Internet de calidad y, con esta\u00a0iniciativa, reduciremos la brecha digital existente entre los concejos y el\u00a0resto del Valle\u201d, ha concluido Bernal.<\/p>\n<p>Cabe se\u00f1alar que la fibra \u00f3ptica es el medio de transmisi\u00f3n m\u00e1s\u00a0avanzado y el \u00fanico capaz de soportar los servicios de nueva generaci\u00f3n,\u00a0como televisi\u00f3n de alta definici\u00f3n. Las principales ventajas de tener una\u00a0red de fibra \u00f3ptica son muchas: mayores anchos de banda, mayores\u00a0distancias desde la central hasta los usuarios, mayor resistencia a la\u00a0interferencia electromagn\u00e9tica, mayor seguridad, menor degradaci\u00f3n de\u00a0las se\u00f1ales\u2026<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una partida cercana a los 70.000 euros, el Consistorio apuesta por la digitalizaci\u00f3n y la conexi\u00f3n. Pretende dar respuesta as\u00ed a una reivindicaci\u00f3n hist\u00f3rica que se ha visto agravada estos \u00faltimos meses por el confinamiento ocasionado por el Covid-19 Un Valle totalmente digital, y conectado al 100% en\u00a0el menor plazo posible. Bajo la premisa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":18729,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[172],"tags":[],"class_list":["post-18728","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-udala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Con una partida cercana a los 70.000 euros, el Consistorio apuesta por la digitalizaci\u00f3n y la conexi\u00f3n. Pretende dar respuesta as\u00ed a una reivindicaci\u00f3n hist\u00f3rica que se ha visto agravada estos \u00faltimos meses por el confinamiento ocasionado por el Covid-19 Un Valle totalmente digital, y conectado al 100% en\u00a0el menor plazo posible. Bajo la premisa [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-07-01T15:34:08+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/07\/fibra-optica-egues.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"900\" \/>\r\n\t<meta property=\"og:image:height\" content=\"600\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos\",\"datePublished\":\"2020-07-01T15:34:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/\"},\"wordCount\":408,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/fibra-optica-egues.jpg\",\"articleSection\":[\"Udala\"],\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/\",\"name\":\"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/fibra-optica-egues.jpg\",\"datePublished\":\"2020-07-01T15:34:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/fibra-optica-egues.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/fibra-optica-egues.jpg\",\"width\":900,\"height\":600,\"caption\":\"Fibra Optica Egues\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/","og_locale":"eu_ES","og_type":"article","og_title":"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Con una partida cercana a los 70.000 euros, el Consistorio apuesta por la digitalizaci\u00f3n y la conexi\u00f3n. Pretende dar respuesta as\u00ed a una reivindicaci\u00f3n hist\u00f3rica que se ha visto agravada estos \u00faltimos meses por el confinamiento ocasionado por el Covid-19 Un Valle totalmente digital, y conectado al 100% en\u00a0el menor plazo posible. Bajo la premisa [&hellip;]","og_url":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2020-07-01T15:34:08+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/07\/fibra-optica-egues.jpg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos","datePublished":"2020-07-01T15:34:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/"},"wordCount":408,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/07\/fibra-optica-egues.jpg","articleSection":["Udala"],"inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/","url":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/","name":"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/07\/fibra-optica-egues.jpg","datePublished":"2020-07-01T15:34:08+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/07\/fibra-optica-egues.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/07\/fibra-optica-egues.jpg","width":900,"height":600,"caption":"Fibra Optica Egues"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/el-ayuntamiento-del-valle-de-egues-convoca-un-concurso-para-llevar-la-fibra-optica-a-todos-sus-concejos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"El Ayuntamiento del Valle de Eg\u00fc\u00e9s convoca un concurso para llevar la fibra \u00f3ptica a todos sus concejos"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/posts\/18728","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/comments?post=18728"}],"version-history":[{"count":1,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/posts\/18728\/revisions"}],"predecessor-version":[{"id":18731,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/posts\/18728\/revisions\/18731"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/18729"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=18728"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/categories?post=18728"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/tags?post=18728"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}