{"id":18725,"date":"2020-07-01T14:01:39","date_gmt":"2020-07-01T12:01:39","guid":{"rendered":"https:\/\/www.valledeegues.com\/ampliado-el-plazo-de-inscripcion-para-el-campamento-juvenil-eguesibar-lets-go\/"},"modified":"2020-07-01T14:04:08","modified_gmt":"2020-07-01T12:04:08","slug":"eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da","status":"publish","type":"post","link":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/","title":{"rendered":"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><strong>IZEN EMATEAK:<\/strong><\/p><ul>\n<li>Euskarazko txanda: Ekainaren 19tik uztailaren 20ra.<\/li>\n<li>Gaztelaniazko txanda: Ekainaren 19tik abuztuaren 7ra.<\/li>\n<\/ul><p>Esteka honetan:<\/p><p>&#128073;&nbsp;<a href=\"https:\/\/valledeeguesparticipa.com\/participa\/eguesibar-lets-go\/\"><strong> https:\/\/valledeeguesparticipa.com\/participa\/eguesibar-lets-go\/<\/strong><\/a><\/p><p>Informazio gehiago:<\/p><p><strong><a href=\"\/?p=18574\">https:\/\/www.valledeegues.com\/abiertas-inscripciones-en-el-campamento-juvenil-eguesibar-lets-go\/<\/a><\/strong><\/p><p><a href=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go.jpg\" class=\"doc-link doc-jpg doc-group-image\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-large wp-image-18571\" src=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go-721x1024.jpg\" alt=\"\" width=\"721\" height=\"1024\" data-wpmf_image_lightbox=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go-721x1024.jpg\" data-wpmf_size_lightbox=\"large\" data-wpmflightbox=\"1\" srcset=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go-721x1024.jpg 721w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go-211x300.jpg 211w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go-768x1090.jpg 768w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go-1082x1536.jpg 1082w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go-1443x2048.jpg 1443w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go-1320x1874.jpg 1320w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/cartel-eguesibar-lets-go.jpg 1763w\" sizes=\"auto, (max-width: 721px) 100vw, 721px\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>IZEN EMATEAK: Euskarazko txanda: Ekainaren 19tik uztailaren 20ra. Gaztelaniazko txanda: Ekainaren 19tik abuztuaren 7ra. Esteka honetan:&#128073;&nbsp; https:\/\/valledeeguesparticipa.com\/participa\/eguesibar-lets-go\/Informazio gehiago:https:\/\/www.valledeegues.com\/abiertas-inscripciones-en-el-campamento-juvenil-eguesibar-lets-go\/<\/p>\n","protected":false},"author":2,"featured_media":18568,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[552,172],"tags":[],"class_list":["post-18725","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-juventud-eu","category-udala"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"IZEN EMATEAK: Euskarazko txanda: Ekainaren 19tik uztailaren 20ra. Gaztelaniazko txanda: Ekainaren 19tik abuztuaren 7ra. Esteka honetan:&#128073;&nbsp; https:\/\/valledeeguesparticipa.com\/participa\/eguesibar-lets-go\/Informazio gehiago:https:\/\/www.valledeegues.com\/abiertas-inscripciones-en-el-campamento-juvenil-eguesibar-lets-go\/\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2020-07-01T12:01:39+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2020-07-01T12:04:08+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/eguesibar-lets-go.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"900\" \/>\r\n\t<meta property=\"og:image:height\" content=\"600\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA\",\"datePublished\":\"2020-07-01T12:01:39+00:00\",\"dateModified\":\"2020-07-01T12:04:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/\"},\"wordCount\":39,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/eguesibar-lets-go.jpg\",\"articleSection\":[\"JUVENTUD\",\"Udala\"],\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/\",\"name\":\"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/eguesibar-lets-go.jpg\",\"datePublished\":\"2020-07-01T12:01:39+00:00\",\"dateModified\":\"2020-07-01T12:04:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/eguesibar-lets-go.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/eguesibar-lets-go.jpg\",\"width\":900,\"height\":600,\"caption\":\"eguesibar-lets-go\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/","og_locale":"eu_ES","og_type":"article","og_title":"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"IZEN EMATEAK: Euskarazko txanda: Ekainaren 19tik uztailaren 20ra. Gaztelaniazko txanda: Ekainaren 19tik abuztuaren 7ra. Esteka honetan:&#128073;&nbsp; https:\/\/valledeeguesparticipa.com\/participa\/eguesibar-lets-go\/Informazio gehiago:https:\/\/www.valledeegues.com\/abiertas-inscripciones-en-el-campamento-juvenil-eguesibar-lets-go\/","og_url":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2020-07-01T12:01:39+00:00","article_modified_time":"2020-07-01T12:04:08+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/eguesibar-lets-go.jpg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA","datePublished":"2020-07-01T12:01:39+00:00","dateModified":"2020-07-01T12:04:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/"},"wordCount":39,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/eguesibar-lets-go.jpg","articleSection":["JUVENTUD","Udala"],"inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/","url":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/","name":"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/eguesibar-lets-go.jpg","datePublished":"2020-07-01T12:01:39+00:00","dateModified":"2020-07-01T12:04:08+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/eguesibar-lets-go.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2020\/06\/eguesibar-lets-go.jpg","width":900,"height":600,"caption":"eguesibar-lets-go"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eguesibar-lets-go-gazte-kanpaldian-izena-emateko-epea-luzatu-da\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"EGUESIBAR LET\u00b4S GO! GAZTE KANPALDIAN IZENA EMATEKO EPEA LUZATU DA"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/posts\/18725","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/comments?post=18725"}],"version-history":[{"count":2,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/posts\/18725\/revisions"}],"predecessor-version":[{"id":18727,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/posts\/18725\/revisions\/18727"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/18568"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=18725"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/categories?post=18725"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/tags?post=18725"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}