{"id":36737,"date":"2024-07-02T13:11:12","date_gmt":"2024-07-02T11:11:12","guid":{"rendered":"https:\/\/www.valledeegues.com\/?p=36737"},"modified":"2024-09-19T23:09:44","modified_gmt":"2024-09-19T21:09:44","slug":"2024-25-ikasturterako-eskola-jantokirako-laguntzak","status":"publish","type":"noticias","link":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/","title":{"rendered":"2024-25 ikasturterako eskola-jantokirako laguntzak"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p>2024-25 ikasturterako eskola-jantokirako laguntzen deialdia onartu du Tokiko Gobernu Batzarrak.<\/p><p><strong>ESKAERA EGITEKO EPEA IRAILAREN 5etik 13ra.<\/strong><\/p><div class=\"row\">\n<div class=\"col-md-12 col-xs-12\">&#12644;&#12644;&#12644;&#12644;<br>\nEskaerak udal erregistro elektronikoaren bidez edo aurrez aurre aurkeztu ahal izango dira Oinarrizko Gizarte Zerbitzuan.<br>\nAbuztuaren 1etik aurrera egongo da eskuragarri aurrez hitzordua hartzeko erreserba, webgunean edo 012 telefonoaren bidez.<\/div>\n<div>&#12644;&#12644;&#12644;&#12644;<\/div>\n<div class=\"col-md-12 col-xs-12\">Informazio gehiago:<\/div>\n<div class=\"col-md-12 col-xs-12\"><span class=\"wpmf_mce-wrap\" style=\"overflow: hidden\" data-file=\"36733\"><a class=\"wpmf-defile wpmf_mce-single-child doc-link doc-pdf doc-group-pdf\" href=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/07\/bases.pdf\" target=\"\" rel=\"noopener\" data-id=\"36733\"><span class=\"wpmf_mce-single-child\" style=\"font-weight: bold\">Oinarriak<\/span><br>\n<span class=\"wpmf_mce-single-child\" style=\"font-weight: normal;font-size: 0.8em\"><b class=\"wpmf_mce-single-child\">Tama&ntilde;o : <\/b>908.7 kB<b class=\"wpmf_mce-single-child\"> Formato : <\/b>PDF<\/span><\/a><\/span><br>\n&#12644;&#12644;&#12644;&#12644;<br>\n<strong>Tokiko Gobernu Batzarrean onartuak, NAOn argitaratzeke.<\/strong><\/div>\n<\/div>\n","protected":false},"author":2,"featured_media":36735,"template":"","format":"standard","meta":{"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"eu\":2,\"es\":2}}"],"_edit_lock":["1726780048:2"],"_edit_last":["2"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"cptr_related":["a:0:{}"],"_thumbnail_id":["36735"],"_last_translation_edit_mode":["native-editor"],"boxed_layout_shadow_size":["0"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_theme_options_build":["696f71999b1ad"],"_oembed_cea615d7a3be58e90dd93d0b54b846b4":["<iframe title=\"Mi nombre es Harvey Milk - Trailer espa\u00f1ol\" width=\"1140\" height=\"641\" src=\"https:\/\/www.youtube.com\/embed\/3uI5o8THOzg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_cea615d7a3be58e90dd93d0b54b846b4":["1719963795"],"_yoast_wpseo_primary_category":["26"],"_wpml_media_has_media":["1"]},"class_list":["post-36737","noticias","type-noticias","status-publish","format-standard","has-post-thumbnail","hentry","categorianoticias-albisteak","categorianoticias-sin-categorizar-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>2024-25 ikasturterako eskola-jantokirako laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"2024-25 ikasturterako eskola-jantokirako laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"2024-25 ikasturterako eskola-jantokirako laguntzen deialdia onartu du Tokiko Gobernu Batzarrak.ESKAERA EGITEKO EPEA IRAILAREN 5etik 13ra. &#12644;&#12644;&#12644;&#12644; Eskaerak udal erregistro elektronikoaren bidez edo aurrez aurre aurkeztu ahal izango dira Oinarrizko Gizarte Zerbitzuan. Abuztuaren 1etik aurrera egongo da eskuragarri aurrez hitzordua hartzeko erreserba, webgunean edo 012 telefonoaren bidez. &#12644;&#12644;&#12644;&#12644; Informazio gehiago: Oinarriak Tama&ntilde;o : 908.7 kB Formato [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-07-02T11:11:12+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-09-19T21:09:44+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/07\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"894\" \/>\r\n\t<meta property=\"og:image:height\" content=\"403\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"2024-25 ikasturterako eskola-jantokirako laguntzak\",\"datePublished\":\"2024-07-02T11:11:12+00:00\",\"dateModified\":\"2024-09-19T21:09:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/\"},\"wordCount\":63,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg\",\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/\",\"name\":\"2024-25 ikasturterako eskola-jantokirako laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg\",\"datePublished\":\"2024-07-02T11:11:12+00:00\",\"dateModified\":\"2024-09-19T21:09:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg\",\"width\":894,\"height\":403},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2024-25 ikasturterako eskola-jantokirako laguntzak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2024-25 ikasturterako eskola-jantokirako laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/","og_locale":"eu_ES","og_type":"article","og_title":"2024-25 ikasturterako eskola-jantokirako laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"2024-25 ikasturterako eskola-jantokirako laguntzen deialdia onartu du Tokiko Gobernu Batzarrak.ESKAERA EGITEKO EPEA IRAILAREN 5etik 13ra. &#12644;&#12644;&#12644;&#12644; Eskaerak udal erregistro elektronikoaren bidez edo aurrez aurre aurkeztu ahal izango dira Oinarrizko Gizarte Zerbitzuan. Abuztuaren 1etik aurrera egongo da eskuragarri aurrez hitzordua hartzeko erreserba, webgunean edo 012 telefonoaren bidez. &#12644;&#12644;&#12644;&#12644; Informazio gehiago: Oinarriak Tama&ntilde;o : 908.7 kB Formato [&hellip;]","og_url":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2024-07-02T11:11:12+00:00","article_modified_time":"2024-09-19T21:09:44+00:00","og_image":[{"width":894,"height":403,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/07\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"2024-25 ikasturterako eskola-jantokirako laguntzak","datePublished":"2024-07-02T11:11:12+00:00","dateModified":"2024-09-19T21:09:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/"},"wordCount":63,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/07\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg","inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/","url":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/","name":"2024-25 ikasturterako eskola-jantokirako laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/07\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg","datePublished":"2024-07-02T11:11:12+00:00","dateModified":"2024-09-19T21:09:44+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/07\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/07\/comedor-escolar-egues-qbyt7nt28dz2rw9d2qjrwwleiz7o9zq40nsszdgyf2.jpeg","width":894,"height":403},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2024-25-ikasturterako-eskola-jantokirako-laguntzak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"2024-25 ikasturterako eskola-jantokirako laguntzak"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias\/36737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/36735"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=36737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}