{"id":34330,"date":"2024-01-22T09:40:28","date_gmt":"2024-01-22T08:40:28","guid":{"rendered":"https:\/\/www.valledeegues.com\/?p=34330"},"modified":"2024-01-22T09:40:28","modified_gmt":"2024-01-22T08:40:28","slug":"komunikatua-udaletxearen-kondena-publikoa","status":"publish","type":"noticias","link":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/","title":{"rendered":"Komunikatua: Udaletxearen kondena publikoa"},"content":{"rendered":"<div class=\"ql-block\" data-block-id=\"block-ad7b6bc4-fcc3-489f-80bb-94de4dbcca1a\">Joan den ostegunean Sarrigurenen izandako erasoaren aurrean, Eguesibarreko Udalak bere gaitzespena eta gaitzespen publikoa adierazi nahi du emakumeen aurkako edozein indarkeria motaren aurrean. Era berean, familiari babesa eta elkartasuna erakusten diogu, eta lanean jarraitzeko konpromisoa hartzen dugu, emakumeek indarkeriarik gabeko bizitza izateko duten eskubidea gauza dadin.<\/div>\n<div data-block-id=\"block-ad7b6bc4-fcc3-489f-80bb-94de4dbcca1a\"><\/div>\n<div class=\"ql-block\" data-block-id=\"block-b98cef50-fdf9-4e0c-96e0-e0bf6399f0e0\">Gogorarazten da, gainera, biktimei laguntzeko tokiko protokoloa hasiera-hasieratik aktibatu zela, eta Udalaren baliabideek eta kanpoko gainerako baliabideek koordinatuta lan egin dutela.<\/div>\n<div class=\"ql-block ql-align-justify\" data-block-id=\"block-eb041dcf-fb34-4388-bd98-c4583b7641cb\"><\/div>\n","protected":false},"author":2,"featured_media":34328,"template":"","format":"standard","meta":{"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"eu\":2,\"es\":2}}"],"_edit_lock":["1705913266:2"],"_edit_last":["2"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_yoast_wpseo_primary_category":[""],"cptr_related":["a:0:{}"],"_thumbnail_id":["34328"],"_last_translation_edit_mode":["native-editor"],"boxed_layout_shadow_size":["0"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_wpml_media_has_media":["1"],"_theme_options_build":["696f71999b1ad"],"_oembed_cea615d7a3be58e90dd93d0b54b846b4":["<iframe title=\"Mi nombre es Harvey Milk - Trailer espa\u00f1ol\" width=\"1140\" height=\"641\" src=\"https:\/\/www.youtube.com\/embed\/3uI5o8THOzg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>"],"_oembed_time_cea615d7a3be58e90dd93d0b54b846b4":["1705965293"]},"class_list":["post-34330","noticias","type-noticias","status-publish","format-standard","has-post-thumbnail","hentry","categorianoticias-albisteak","categorianoticias-berdintasuna-noticias","categorianoticias-sin-categorizar-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Komunikatua: Udaletxearen kondena publikoa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Komunikatua: Udaletxearen kondena publikoa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Joan den ostegunean Sarrigurenen izandako erasoaren aurrean, Eguesibarreko Udalak bere gaitzespena eta gaitzespen publikoa adierazi nahi du emakumeen aurkako edozein indarkeria motaren aurrean. Era berean, familiari babesa eta elkartasuna erakusten diogu, eta lanean jarraitzeko konpromisoa hartzen dugu, emakumeek indarkeriarik gabeko bizitza izateko duten eskubidea gauza dadin. Gogorarazten da, gainera, biktimei laguntzeko tokiko protokoloa hasiera-hasieratik aktibatu [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2024-01-22T08:40:28+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/01\/banner-web-egues-48.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"940\" \/>\r\n\t<meta property=\"og:image:height\" content=\"425\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"Komunikatua: Udaletxearen kondena publikoa\",\"datePublished\":\"2024-01-22T08:40:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/\"},\"wordCount\":71,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/banner-web-egues-48.png\",\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/\",\"name\":\"Komunikatua: Udaletxearen kondena publikoa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/banner-web-egues-48.png\",\"datePublished\":\"2024-01-22T08:40:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/banner-web-egues-48.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/banner-web-egues-48.png\",\"width\":940,\"height\":425},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/komunikatua-udaletxearen-kondena-publikoa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Komunikatua: Udaletxearen kondena publikoa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Komunikatua: Udaletxearen kondena publikoa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/","og_locale":"eu_ES","og_type":"article","og_title":"Komunikatua: Udaletxearen kondena publikoa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Joan den ostegunean Sarrigurenen izandako erasoaren aurrean, Eguesibarreko Udalak bere gaitzespena eta gaitzespen publikoa adierazi nahi du emakumeen aurkako edozein indarkeria motaren aurrean. Era berean, familiari babesa eta elkartasuna erakusten diogu, eta lanean jarraitzeko konpromisoa hartzen dugu, emakumeek indarkeriarik gabeko bizitza izateko duten eskubidea gauza dadin. Gogorarazten da, gainera, biktimei laguntzeko tokiko protokoloa hasiera-hasieratik aktibatu [&hellip;]","og_url":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2024-01-22T08:40:28+00:00","og_image":[{"width":940,"height":425,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/01\/banner-web-egues-48.png","type":"image\/png"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"Komunikatua: Udaletxearen kondena publikoa","datePublished":"2024-01-22T08:40:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/"},"wordCount":71,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/01\/banner-web-egues-48.png","inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/","url":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/","name":"Komunikatua: Udaletxearen kondena publikoa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/01\/banner-web-egues-48.png","datePublished":"2024-01-22T08:40:28+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/01\/banner-web-egues-48.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/01\/banner-web-egues-48.png","width":940,"height":425},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/komunikatua-udaletxearen-kondena-publikoa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Komunikatua: Udaletxearen kondena publikoa"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias\/34330","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/34328"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=34330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}