{"id":31003,"date":"2023-05-22T09:19:15","date_gmt":"2023-05-22T07:19:15","guid":{"rendered":"https:\/\/www.valledeegues.com\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/"},"modified":"2023-05-22T09:21:18","modified_gmt":"2023-05-22T07:21:18","slug":"abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto","status":"publish","type":"noticias","link":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/","title":{"rendered":"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p>Abuztuaren 1etik 25era egongo den Familia Atsedenerako zerbitzuaren aurreinskripzioen epea irekita dago.<\/p><p>Erroldatutako familientzako plaza eskaera maiatzaren 22tik ekainaren 4ra bitartean egin daiteke Eguesibarko Udalaren webguneko formularioaren bidez: <strong><a href=\"https:\/\/muniinspeccion.web.app\/publico\/contestar\/wXRsqAjyNuHBIUqXFMrI\">HEMEN<\/a><\/strong><\/p><p>1-6 urte bitarteko adingabeentzat zaintza eta arreta ludikoan oinarrituta dagoen zerbitzua da. Abuztuan zehar zerbitzua erabili nahi diren orduak, egunak eta asteak aukeratu daitezke. Prezioa 2 &euro;\/orduko: gutxienez 2 ordu eguneko, gehienez 50 ordu hilean.<\/p><p>Informazio gehiagorako: Izen-emate fitxan, FAZera deituz edo joanez (Urbasa kalea, 129, Sarriguren) 948 165651 <a href=\"mailto:caf@egues.es\">caf@egues.es<\/a><\/p>\n","protected":false},"author":2,"featured_media":31001,"template":"","format":"standard","meta":{"_wpml_word_count":["{\"total\":148,\"to_translate\":{\"eu\":148}}"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"_wpml_location_migration_done":["1"],"cptr_related":["a:0:{}"],"boxed_layout_shadow_size":["0"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_thumbnail_id":["31001"],"_edit_lock":["1684740241:2"],"_edit_last":["2"],"_last_translation_edit_mode":["native-editor"],"_theme_options_build":["696f71999b1ad"],"_wpml_media_has_media":["1"],"_yoast_wpseo_primary_category":["308"]},"class_list":["post-31003","noticias","type-noticias","status-publish","format-standard","has-post-thumbnail","hentry","categorianoticias-albisteak","categorianoticias-faz-noticias","categorianoticias-izen-emateak","categorianoticias-sin-categorizar-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Abuztuaren 1etik 25era egongo den Familia Atsedenerako zerbitzuaren aurreinskripzioen epea irekita dago.Erroldatutako familientzako plaza eskaera maiatzaren 22tik ekainaren 4ra bitartean egin daiteke Eguesibarko Udalaren webguneko formularioaren bidez: HEMEN1-6 urte bitarteko adingabeentzat zaintza eta arreta ludikoan oinarrituta dagoen zerbitzua da. Abuztuan zehar zerbitzua erabili nahi diren orduak, egunak eta asteak aukeratu daitezke. Prezioa 2 &euro;\/orduko: gutxienez [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-05-22T07:19:15+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-05-22T07:21:18+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/05\/copia-de-diseno-sin-titulo-10.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO\",\"datePublished\":\"2023-05-22T07:19:15+00:00\",\"dateModified\":\"2023-05-22T07:21:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/\"},\"wordCount\":85,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/copia-de-diseno-sin-titulo-10.jpg\",\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/\",\"name\":\"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/copia-de-diseno-sin-titulo-10.jpg\",\"datePublished\":\"2023-05-22T07:19:15+00:00\",\"dateModified\":\"2023-05-22T07:21:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/copia-de-diseno-sin-titulo-10.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/copia-de-diseno-sin-titulo-10.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"copia-de-diseno-sin-titulo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/","og_locale":"eu_ES","og_type":"article","og_title":"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Abuztuaren 1etik 25era egongo den Familia Atsedenerako zerbitzuaren aurreinskripzioen epea irekita dago.Erroldatutako familientzako plaza eskaera maiatzaren 22tik ekainaren 4ra bitartean egin daiteke Eguesibarko Udalaren webguneko formularioaren bidez: HEMEN1-6 urte bitarteko adingabeentzat zaintza eta arreta ludikoan oinarrituta dagoen zerbitzua da. Abuztuan zehar zerbitzua erabili nahi diren orduak, egunak eta asteak aukeratu daitezke. Prezioa 2 &euro;\/orduko: gutxienez [&hellip;]","og_url":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2023-05-22T07:19:15+00:00","article_modified_time":"2023-05-22T07:21:18+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/05\/copia-de-diseno-sin-titulo-10.jpg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO","datePublished":"2023-05-22T07:19:15+00:00","dateModified":"2023-05-22T07:21:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/"},"wordCount":85,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/05\/copia-de-diseno-sin-titulo-10.jpg","inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/","url":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/","name":"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/05\/copia-de-diseno-sin-titulo-10.jpg","datePublished":"2023-05-22T07:19:15+00:00","dateModified":"2023-05-22T07:21:18+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/05\/copia-de-diseno-sin-titulo-10.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/05\/copia-de-diseno-sin-titulo-10.jpg","width":1920,"height":1080,"caption":"copia-de-diseno-sin-titulo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/abierto-el-plazo-de-inscripciones-para-el-respiro-familiar-de-agosto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"ABUZTUAN IZANGO DEN FAMILIA ATSEDENERAKO ZERBITZURAKO IZEN-EMATE\u00a0 EPEA IREKITA DAGO"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias\/31003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/31001"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=31003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}