{"id":29980,"date":"2023-03-30T08:24:42","date_gmt":"2023-03-30T06:24:42","guid":{"rendered":"https:\/\/www.valledeegues.com\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/"},"modified":"2023-03-30T08:28:39","modified_gmt":"2023-03-30T06:28:39","slug":"el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril","status":"publish","type":"noticias","link":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/","title":{"rendered":"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p>Data aldaketa: Azkenean,&nbsp; apirilaren 18rako programatuta zegoen &ldquo;Nola izan erreferente haur eta gazteen erantzunkidetasunean&rdquo; tailerra. apirilaren 24ean egingo da, 17:00etatik 19:00etara FAZen.<\/p><p>Elkarrekin bizi diren bikote helduentzat da lantegia, baita ingurune hurbilean haur eta nerabeak dituzten pertsona eta profesionalentzat ere. Saioa bat dator Berdintasun Arloa azken hilabeteotan erantzunkidetasunari buruz egiten ari den tailerrekin.<\/p><p>Magal&iacute; Mart&iacute;nez Solim&aacute;n, generoan, berdintasunean, ahalduntzean eta lidergo-politiketan aditua, izango da berriro FAZeko erabilera anitzeko aretoan tailer horiek emateko arduraduna (Urbasa kalea, 129. Sarriguren).<\/p><p>Izen emateak: martxoaren 15etik apirilaren 11ra FAZen 948 16 56 51 telefonoan edo caf-faz@egues.es posta elektronikoan. Familientzako atseden-zerbitzua egongo da, apirilaren 5a baino lehen eskatuta.<\/p><p>Ekintza hau bat dator Eguesibarko Genero Berdintasunerako II. Planaren eta Eguesibarko Kontziliazioaren aldeko Toki Itunaren ekintzekin.<\/p><p>Halaber, Berdintasun Sailak oraintsu koordinatutako bateragarritasunari eta erantzunkidetasunari buruzko podcast-ak entzun ditzakezue&nbsp;<a href=\"\/?p=28944\">esteka honetan<\/a>.<\/p>\n","protected":false},"author":2,"featured_media":29769,"template":"","format":"standard","meta":{"_wpml_word_count":["{\"total\":273,\"to_translate\":{\"eu\":273}}"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"_wpml_location_migration_done":["1"],"cptr_related":["a:0:{}"],"boxed_layout_shadow_size":["0"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_yoast_wpseo_primary_category":["195"],"_thumbnail_id":["29769"],"_edit_lock":["1680158424:2"],"_theme_options_build":["696f71999b1ad"],"_edit_last":["2"],"_wpml_media_has_media":["1"],"_last_translation_edit_mode":["native-editor"]},"class_list":["post-29980","noticias","type-noticias","status-publish","format-standard","has-post-thumbnail","hentry","categorianoticias-albisteak","categorianoticias-berdintasuna-noticias","categorianoticias-sin-categorizar-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Data aldaketa: Azkenean,&nbsp; apirilaren 18rako programatuta zegoen &ldquo;Nola izan erreferente haur eta gazteen erantzunkidetasunean&rdquo; tailerra. apirilaren 24ean egingo da, 17:00etatik 19:00etara FAZen.Elkarrekin bizi diren bikote helduentzat da lantegia, baita ingurune hurbilean haur eta nerabeak dituzten pertsona eta profesionalentzat ere. Saioa bat dator Berdintasun Arloa azken hilabeteotan erantzunkidetasunari buruz egiten ari den tailerrekin.Magal&iacute; Mart&iacute;nez Solim&aacute;n, generoan, [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2023-03-30T06:24:42+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2023-03-30T06:28:39+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/03\/copia-de-diseno-sin-titulo-1-1.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA\",\"datePublished\":\"2023-03-30T06:24:42+00:00\",\"dateModified\":\"2023-03-30T06:28:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/\"},\"wordCount\":143,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/copia-de-diseno-sin-titulo-1-1.jpg\",\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/\",\"name\":\"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/copia-de-diseno-sin-titulo-1-1.jpg\",\"datePublished\":\"2023-03-30T06:24:42+00:00\",\"dateModified\":\"2023-03-30T06:28:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/copia-de-diseno-sin-titulo-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/copia-de-diseno-sin-titulo-1-1.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"copia-de-diseno-sin-titulo-1\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/","og_locale":"eu_ES","og_type":"article","og_title":"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Data aldaketa: Azkenean,&nbsp; apirilaren 18rako programatuta zegoen &ldquo;Nola izan erreferente haur eta gazteen erantzunkidetasunean&rdquo; tailerra. apirilaren 24ean egingo da, 17:00etatik 19:00etara FAZen.Elkarrekin bizi diren bikote helduentzat da lantegia, baita ingurune hurbilean haur eta nerabeak dituzten pertsona eta profesionalentzat ere. Saioa bat dator Berdintasun Arloa azken hilabeteotan erantzunkidetasunari buruz egiten ari den tailerrekin.Magal&iacute; Mart&iacute;nez Solim&aacute;n, generoan, [&hellip;]","og_url":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2023-03-30T06:24:42+00:00","article_modified_time":"2023-03-30T06:28:39+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/03\/copia-de-diseno-sin-titulo-1-1.jpg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA","datePublished":"2023-03-30T06:24:42+00:00","dateModified":"2023-03-30T06:28:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/"},"wordCount":143,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/03\/copia-de-diseno-sin-titulo-1-1.jpg","inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/","url":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/","name":"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/03\/copia-de-diseno-sin-titulo-1-1.jpg","datePublished":"2023-03-30T06:24:42+00:00","dateModified":"2023-03-30T06:28:39+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/03\/copia-de-diseno-sin-titulo-1-1.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2023\/03\/copia-de-diseno-sin-titulo-1-1.jpg","width":1920,"height":1080,"caption":"copia-de-diseno-sin-titulo-1"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/el-taller-como-ser-referente-en-corresponsabilidad-para-peques-y-jovenes-se-celebrara-el-24-de-abril\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"\u201cNOLA IZAN ERREFERENTE HAUR ETA GAZTEEN ERANTZUNKIDETASUNEAN\u201d TAILERRA APIRILAREN 24EAN EGINGO DA"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias\/29980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/29769"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=29980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}