{"id":27389,"date":"2022-07-05T09:24:27","date_gmt":"2022-07-05T07:24:27","guid":{"rendered":"https:\/\/www.valledeegues.com\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/"},"modified":"2022-07-05T13:10:22","modified_gmt":"2022-07-05T11:10:22","slug":"programa-de-busqueda-de-empleo-en-el-valle-de-egues","status":"publish","type":"noticias","link":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/","title":{"rendered":"Eguesibarren lana bilatzeko programa"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p>Informazio hitzaldiak, <strong>uztailaren 19an edo 20an<\/strong>, Udaletxean, 10:00etan (Oinarrizko Gizarte Zerbitzutik sartzen).<\/p><p><span class=\"wpmf_mce-wrap\" style=\"overflow: hidden\" data-file=\"27392\"><a class=\"wpmf-defile wpmf_mce-single-child doc-link doc-pdf doc-group-pdf\" href=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2022\/07\/folleto.pdf\" target=\"\" data-id=\"27392\" rel=\"noopener\">Eskuorria<br>\n<span class=\"wpmf_mce-single-child\" style=\"font-weight: normal;font-size: 0.8em\"><b class=\"wpmf_mce-single-child\">Tama&ntilde;o : <\/b>1.1 MB<b class=\"wpmf_mce-single-child\"> Formato : <\/b>PDF<\/span><\/a><\/span><\/p><p>&nbsp;<\/p>\n","protected":false},"author":2,"featured_media":27384,"template":"","format":"standard","meta":{"_wpml_word_count":["{\"total\":53,\"to_translate\":{\"eu\":53}}"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"_wpml_location_migration_done":["1"],"cptr_related":["a:0:{}"],"boxed_layout_shadow_size":["0"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_thumbnail_id":["27384"],"_edit_lock":["1657019286:2"],"_theme_options_build":["696f71999b1ad"],"_edit_last":["2"],"_last_translation_edit_mode":["native-editor"],"_wpml_media_has_media":["1"],"_yoast_wpseo_primary_category":["1"]},"class_list":["post-27389","noticias","type-noticias","status-publish","format-standard","has-post-thumbnail","hentry","categorianoticias-albisteak","categorianoticias-enplegua","categorianoticias-sin-categorizar-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Eguesibarren lana bilatzeko programa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Eguesibarren lana bilatzeko programa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Informazio hitzaldiak, uztailaren 19an edo 20an, Udaletxean, 10:00etan (Oinarrizko Gizarte Zerbitzutik sartzen).Eskuorria Tama&ntilde;o : 1.1 MB Formato : PDF&nbsp;\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-07-05T07:24:27+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2022-07-05T11:10:22+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2022\/07\/ach-diptico-1.7.22-definitivo_page-0001.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"880\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1243\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"Eguesibarren lana bilatzeko programa\",\"datePublished\":\"2022-07-05T07:24:27+00:00\",\"dateModified\":\"2022-07-05T11:10:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/\"},\"wordCount\":23,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ach-diptico-1.7.22-definitivo_page-0001.jpg\",\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/\",\"name\":\"Eguesibarren lana bilatzeko programa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ach-diptico-1.7.22-definitivo_page-0001.jpg\",\"datePublished\":\"2022-07-05T07:24:27+00:00\",\"dateModified\":\"2022-07-05T11:10:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ach-diptico-1.7.22-definitivo_page-0001.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/ach-diptico-1.7.22-definitivo_page-0001.jpg\",\"width\":880,\"height\":1243,\"caption\":\"ach-diptico-1.7.22-definitivo_page-0001\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eguesibarren lana bilatzeko programa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eguesibarren lana bilatzeko programa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/","og_locale":"eu_ES","og_type":"article","og_title":"Eguesibarren lana bilatzeko programa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Informazio hitzaldiak, uztailaren 19an edo 20an, Udaletxean, 10:00etan (Oinarrizko Gizarte Zerbitzutik sartzen).Eskuorria Tama&ntilde;o : 1.1 MB Formato : PDF&nbsp;","og_url":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2022-07-05T07:24:27+00:00","article_modified_time":"2022-07-05T11:10:22+00:00","og_image":[{"width":880,"height":1243,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2022\/07\/ach-diptico-1.7.22-definitivo_page-0001.jpg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"Eguesibarren lana bilatzeko programa","datePublished":"2022-07-05T07:24:27+00:00","dateModified":"2022-07-05T11:10:22+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/"},"wordCount":23,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2022\/07\/ach-diptico-1.7.22-definitivo_page-0001.jpg","inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/","url":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/","name":"Eguesibarren lana bilatzeko programa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2022\/07\/ach-diptico-1.7.22-definitivo_page-0001.jpg","datePublished":"2022-07-05T07:24:27+00:00","dateModified":"2022-07-05T11:10:22+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2022\/07\/ach-diptico-1.7.22-definitivo_page-0001.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2022\/07\/ach-diptico-1.7.22-definitivo_page-0001.jpg","width":880,"height":1243,"caption":"ach-diptico-1.7.22-definitivo_page-0001"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/programa-de-busqueda-de-empleo-en-el-valle-de-egues\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Eguesibarren lana bilatzeko programa"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias\/27389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/27384"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=27389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}