{"id":25136,"date":"2022-01-28T10:54:38","date_gmt":"2022-01-28T09:54:38","guid":{"rendered":"https:\/\/www.valledeegues.com\/sesion-pleno-01-02-2022-ordinaria\/"},"modified":"2022-01-28T10:56:38","modified_gmt":"2022-01-28T09:56:38","slug":"sesion-pleno-01-02-2022-ordinaria","status":"publish","type":"noticias","link":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/","title":{"rendered":"UDALBATZAREN OHIKO BILKURA 2022\/02\/01"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p data-pm-slice=\"1 1 []\">Otsailaren 1ean, asteartea, arratsaldeko 18:00etan Udalbatzak ohiko bilkura egingo du.<\/p><p data-pm-slice=\"1 1 []\"><span class=\"wpmf_mce-wrap\" style=\"overflow: hidden\" data-file=\"25131\"><a class=\"wpmf-defile wpmf_mce-single-child doc-link doc-pdf doc-group-pdf\" href=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2022\/01\/pleno01022022_agenda_220201.pdf\" target=\"\" rel=\"noopener\" data-id=\"25131\"><strong>Gai zerrenda<\/strong><br>\n<span class=\"wpmf_mce-single-child\" style=\"font-weight: normal;font-size: 0.8em\"><b class=\"wpmf_mce-single-child\">Tama&ntilde;o : <\/b>176.5 kB<b class=\"wpmf_mce-single-child\"> Formato : <\/b>PDF<\/span><\/a><\/span><span class=\"wpmf_mce-wrap\" style=\"overflow: hidden\" data-file=\"25133\"><a class=\"wpmf-defile wpmf_mce-single-child doc-link doc-pdf doc-group-pdf\" href=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2022\/01\/pleno01022022_other_conv_8_220201.pdf\" target=\"\" rel=\"noopener\" data-id=\"25133\"><span class=\"wpmf_mce-single-child\" style=\"font-weight: bold\">PSN-ren mozioa, isunak&nbsp;<\/span><br>\n<span class=\"wpmf_mce-single-child\" style=\"font-weight: normal;font-size: 0.8em\"><b class=\"wpmf_mce-single-child\">Tama&ntilde;o : <\/b>474.9 kB<b class=\"wpmf_mce-single-child\"> Formato : <\/b>PDF<\/span><\/a><\/span><\/p><p data-pm-slice=\"1 1 []\">Bilkurarako esteka: <a class=\"linkStyle\" title=\"https:\/\/actas.valledeegues.com\/session\/sessionDetail\/ff8080817e2afd1a017e9ba019cd0095\" href=\"https:\/\/actas.valledeegues.com\/session\/sessionDetail\/ff8080817e2afd1a017e9ba019cd0095\" data-toggle=\"tooltip\">Ohiko bilkura 01\/02\/2022<\/a><\/p>\n","protected":false},"author":2,"featured_media":24321,"template":"","format":"standard","meta":{"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"eu\":56,\"es\":56}}"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"_wpml_location_migration_done":["1"],"cptr_related":["a:0:{}"],"boxed_layout_shadow_size":["0"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_yoast_wpseo_primary_category":["26"],"_thumbnail_id":["24321"],"_edit_lock":["1643363659:2"],"_edit_last":["2"],"_wpml_media_has_media":["1"],"_last_translation_edit_mode":["native-editor"],"_theme_options_build":["696f71999b1ad"]},"class_list":["post-25136","noticias","type-noticias","status-publish","format-standard","has-post-thumbnail","hentry","categorianoticias-albisteak","categorianoticias-sin-categorizar-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>UDALBATZAREN OHIKO BILKURA 2022\/02\/01 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"UDALBATZAREN OHIKO BILKURA 2022\/02\/01 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Otsailaren 1ean, asteartea, arratsaldeko 18:00etan Udalbatzak ohiko bilkura egingo du.Gai zerrenda Tama&ntilde;o : 176.5 kB Formato : PDFPSN-ren mozioa, isunak&nbsp; Tama&ntilde;o : 474.9 kB Formato : PDFBilkurarako esteka: Ohiko bilkura 01\/02\/2022\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2022-01-28T09:54:38+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2022-01-28T09:56:38+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/11\/ayuntamiento-sarriguren-19-egues.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"900\" \/>\r\n\t<meta property=\"og:image:height\" content=\"675\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"UDALBATZAREN OHIKO BILKURA 2022\\\/02\\\/01\",\"datePublished\":\"2022-01-28T09:54:38+00:00\",\"dateModified\":\"2022-01-28T09:56:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/\"},\"wordCount\":32,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ayuntamiento-sarriguren-19-egues.jpg\",\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/\",\"name\":\"UDALBATZAREN OHIKO BILKURA 2022\\\/02\\\/01 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ayuntamiento-sarriguren-19-egues.jpg\",\"datePublished\":\"2022-01-28T09:54:38+00:00\",\"dateModified\":\"2022-01-28T09:56:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ayuntamiento-sarriguren-19-egues.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/ayuntamiento-sarriguren-19-egues.jpg\",\"width\":900,\"height\":675,\"caption\":\"ayuntamiento-sarriguren-19-egues\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/sesion-pleno-01-02-2022-ordinaria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UDALBATZAREN OHIKO BILKURA 2022\\\/02\\\/01\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UDALBATZAREN OHIKO BILKURA 2022\/02\/01 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/","og_locale":"eu_ES","og_type":"article","og_title":"UDALBATZAREN OHIKO BILKURA 2022\/02\/01 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Otsailaren 1ean, asteartea, arratsaldeko 18:00etan Udalbatzak ohiko bilkura egingo du.Gai zerrenda Tama&ntilde;o : 176.5 kB Formato : PDFPSN-ren mozioa, isunak&nbsp; Tama&ntilde;o : 474.9 kB Formato : PDFBilkurarako esteka: Ohiko bilkura 01\/02\/2022","og_url":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2022-01-28T09:54:38+00:00","article_modified_time":"2022-01-28T09:56:38+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/11\/ayuntamiento-sarriguren-19-egues.jpg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"UDALBATZAREN OHIKO BILKURA 2022\/02\/01","datePublished":"2022-01-28T09:54:38+00:00","dateModified":"2022-01-28T09:56:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/"},"wordCount":32,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/11\/ayuntamiento-sarriguren-19-egues.jpg","inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/","url":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/","name":"UDALBATZAREN OHIKO BILKURA 2022\/02\/01 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/11\/ayuntamiento-sarriguren-19-egues.jpg","datePublished":"2022-01-28T09:54:38+00:00","dateModified":"2022-01-28T09:56:38+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/11\/ayuntamiento-sarriguren-19-egues.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/11\/ayuntamiento-sarriguren-19-egues.jpg","width":900,"height":675,"caption":"ayuntamiento-sarriguren-19-egues"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/sesion-pleno-01-02-2022-ordinaria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"UDALBATZAREN OHIKO BILKURA 2022\/02\/01"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias\/25136","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/24321"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=25136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}