{"id":23810,"date":"2021-10-15T10:05:50","date_gmt":"2021-10-15T08:05:50","guid":{"rendered":"https:\/\/www.valledeegues.com\/?p=23810"},"modified":"2021-10-15T10:07:37","modified_gmt":"2021-10-15T08:07:37","slug":"elikagaien-manipulaziorako-ikastaroa","status":"publish","type":"noticias","link":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/","title":{"rendered":"Elikagaien manipulaziorako ikastaroa"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p>APROENAk, Udalak diruz lagundutako gizarte-ekintzako proiektuaren bidez, elikagaien manipulatzailearen ikastaroa eskaintzen du, enpleguari laguntzeko tresna gisa balio dezan. Honako irudi hauetan aurkituko dituzu datuak:<\/p><p><span class=\"wpmf_mce-wrap\" style=\"overflow: hidden\" data-file=\"23811\"><a class=\"wpmf-defile wpmf_mce-single-child doc-link doc-pdf doc-group-pdf\" href=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/10\/cartel-sarri-eusk.pdf\" target=\"\" data-id=\"23811\" rel=\"noopener\"><span class=\"wpmf_mce-single-child\" style=\"font-weight: bold\">Cartel Sarri Eusk<\/span><br>\n<span class=\"wpmf_mce-single-child\" style=\"font-weight: normal;font-size: 0.8em\"><b class=\"wpmf_mce-single-child\">Tama&ntilde;o : <\/b>413.4 kB<b class=\"wpmf_mce-single-child\"> Formato : <\/b>PDF<\/span><\/a><\/span><\/p>\n","protected":false},"author":2,"featured_media":23813,"template":"","format":"standard","meta":{"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"eu\":2,\"es\":2}}"],"_edit_lock":["1634285146:2"],"_edit_last":["2"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"cptr_related":["a:0:{}"],"_thumbnail_id":["23813"],"_last_translation_edit_mode":["native-editor"],"boxed_layout_shadow_size":["0"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_wpml_media_has_media":["1"],"_theme_options_build":["696f71999b1ad"]},"class_list":["post-23810","noticias","type-noticias","status-publish","format-standard","has-post-thumbnail","hentry","categorianoticias-albisteak","categorianoticias-enplegua","categorianoticias-sin-categorizar-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Elikagaien manipulaziorako ikastaroa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Elikagaien manipulaziorako ikastaroa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"APROENAk, Udalak diruz lagundutako gizarte-ekintzako proiektuaren bidez, elikagaien manipulatzailearen ikastaroa eskaintzen du, enpleguari laguntzeko tresna gisa balio dezan. Honako irudi hauetan aurkituko dituzu datuak:Cartel Sarri Eusk Tama&ntilde;o : 413.4 kB Formato : PDF\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2021-10-15T08:05:50+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2021-10-15T08:07:37+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/10\/cartel-sarri-eusk_page-0001-scaled.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1810\" \/>\r\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"Elikagaien manipulaziorako ikastaroa\",\"datePublished\":\"2021-10-15T08:05:50+00:00\",\"dateModified\":\"2021-10-15T08:07:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/\"},\"wordCount\":35,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cartel-sarri-eusk_page-0001-scaled.jpg\",\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/\",\"name\":\"Elikagaien manipulaziorako ikastaroa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cartel-sarri-eusk_page-0001-scaled.jpg\",\"datePublished\":\"2021-10-15T08:05:50+00:00\",\"dateModified\":\"2021-10-15T08:07:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cartel-sarri-eusk_page-0001-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/cartel-sarri-eusk_page-0001-scaled.jpg\",\"width\":1810,\"height\":2560,\"caption\":\"Cartel Sarri Eusk Page 0001\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/elikagaien-manipulaziorako-ikastaroa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Elikagaien manipulaziorako ikastaroa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Elikagaien manipulaziorako ikastaroa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/","og_locale":"eu_ES","og_type":"article","og_title":"Elikagaien manipulaziorako ikastaroa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"APROENAk, Udalak diruz lagundutako gizarte-ekintzako proiektuaren bidez, elikagaien manipulatzailearen ikastaroa eskaintzen du, enpleguari laguntzeko tresna gisa balio dezan. Honako irudi hauetan aurkituko dituzu datuak:Cartel Sarri Eusk Tama&ntilde;o : 413.4 kB Formato : PDF","og_url":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2021-10-15T08:05:50+00:00","article_modified_time":"2021-10-15T08:07:37+00:00","og_image":[{"width":1810,"height":2560,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/10\/cartel-sarri-eusk_page-0001-scaled.jpg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"Elikagaien manipulaziorako ikastaroa","datePublished":"2021-10-15T08:05:50+00:00","dateModified":"2021-10-15T08:07:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/"},"wordCount":35,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/10\/cartel-sarri-eusk_page-0001-scaled.jpg","inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/","url":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/","name":"Elikagaien manipulaziorako ikastaroa - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/10\/cartel-sarri-eusk_page-0001-scaled.jpg","datePublished":"2021-10-15T08:05:50+00:00","dateModified":"2021-10-15T08:07:37+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/10\/cartel-sarri-eusk_page-0001-scaled.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/10\/cartel-sarri-eusk_page-0001-scaled.jpg","width":1810,"height":2560,"caption":"Cartel Sarri Eusk Page 0001"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/elikagaien-manipulaziorako-ikastaroa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Elikagaien manipulaziorako ikastaroa"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias\/23810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/23813"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=23810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}