{"id":21947,"date":"2021-05-04T10:35:10","date_gmt":"2021-05-04T08:35:10","guid":{"rendered":"https:\/\/www.valledeegues.com\/?p=21947"},"modified":"2021-05-04T10:35:40","modified_gmt":"2021-05-04T08:35:40","slug":"2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda","status":"publish","type":"noticias","link":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/","title":{"rendered":"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p><span class=\"wpmf_mce-wrap\" style=\"overflow: hidden\" data-file=\"21942\"><a class=\"wpmf-defile wpmf_mce-single-child doc-link doc-pdf doc-group-pdf\" href=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/05\/pleno-04052021.pdf\" target=\"\" rel=\"noopener\" data-id=\"21942\"><span class=\"wpmf_mce-single-child\" style=\"font-weight: bold\">Osoko bilkura 2021\/05\/04\/<\/span><br>\n<span class=\"wpmf_mce-single-child\" style=\"font-weight: normal;font-size: 0.8em\"><b class=\"wpmf_mce-single-child\">Tamaina : <\/b>185.8 kB<b class=\"wpmf_mce-single-child\"> Formatua : <\/b>PDF<\/span><\/a><\/span><\/p><p><a href=\"https:\/\/valledeeguesparticipa.com\/participa\/pleno-osoko-bilkura\/\"><strong>Parte-hartu:<\/strong><\/a><\/p><blockquote class=\"wp-embedded-content\" data-secret=\"h06IcJ6bUL\"><p><a href=\"https:\/\/valledeeguesparticipa.com\/participa\/pleno-osoko-bilkura\/\">&iquest;Quieres participar en el Pleno Ordinario? Ohiko Osoko Bilkuran parte hartu nahi duzu?<\/a><\/p><\/blockquote><p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&laquo;&iquest;Quieres participar en el Pleno Ordinario? Ohiko Osoko Bilkuran parte hartu nahi duzu?&raquo; &mdash; Valle de Egues Participa\" src=\"https:\/\/valledeeguesparticipa.com\/participa\/pleno-osoko-bilkura\/embed\/#?secret=Q2PTuVdFVo#?secret=h06IcJ6bUL\" data-secret=\"h06IcJ6bUL\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n","protected":false},"author":2,"featured_media":5944,"template":"","format":"standard","meta":{"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"eu\":2,\"es\":2}}"],"_oembed_c458a0c8c08951d05f80e976a3acd4f1":["<blockquote class=\"wp-embedded-content\" data-secret=\"8H6W7OJ2Qa\"><a href=\"https:\/\/valledeeguesparticipa.com\/participa\/pleno-osoko-bilkura\/\">\u00bfQuieres participar en el Pleno Ordinario? Ohiko Osoko Bilkuran parte hartu nahi duzu?<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#171;\u00bfQuieres participar en el Pleno Ordinario? Ohiko Osoko Bilkuran parte hartu nahi duzu?&#187; &#8212; Valle de Egues Participa\" src=\"https:\/\/valledeeguesparticipa.com\/participa\/pleno-osoko-bilkura\/embed\/#?secret=8H6W7OJ2Qa\" data-secret=\"8H6W7OJ2Qa\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>"],"_oembed_time_c458a0c8c08951d05f80e976a3acd4f1":["1620117248"],"_edit_lock":["1620117391:2"],"_edit_last":["2"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"cptr_related":["a:0:{}"],"_last_translation_edit_mode":["native-editor"],"boxed_layout_shadow_size":["0"],"_yoast_wpseo_content_score":["60"],"_thumbnail_id":["5944"],"_wpml_media_has_media":["1"],"_yoast_wpseo_primary_category":["1"],"_theme_options_build":["696f71999b1ad"],"_oembed_5a2619cce0f518d31f21c2d5dfa5309f":["<blockquote class=\"wp-embedded-content\" data-secret=\"h06IcJ6bUL\"><a href=\"https:\/\/valledeeguesparticipa.com\/participa\/pleno-osoko-bilkura\/\">\u00bfQuieres participar en el Pleno Ordinario? Ohiko Osoko Bilkuran parte hartu nahi duzu?<\/a><\/blockquote><iframe class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#171;\u00bfQuieres participar en el Pleno Ordinario? Ohiko Osoko Bilkuran parte hartu nahi duzu?&#187; &#8212; Valle de Egues Participa\" src=\"https:\/\/valledeeguesparticipa.com\/participa\/pleno-osoko-bilkura\/embed\/#?secret=Q2PTuVdFVo#?secret=h06IcJ6bUL\" data-secret=\"h06IcJ6bUL\" width=\"500\" height=\"282\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe>"],"_oembed_time_5a2619cce0f518d31f21c2d5dfa5309f":["1777783876"]},"class_list":["post-21947","noticias","type-noticias","status-publish","format-standard","has-post-thumbnail","hentry","categorianoticias-albisteak","categorianoticias-sin-categorizar-noticias","categorianoticias-udala-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Osoko bilkura 2021\/05\/04\/ Tamaina : 185.8 kB Formatua : PDFParte-hartu:&iquest;Quieres participar en el Pleno Ordinario? Ohiko Osoko Bilkuran parte hartu nahi duzu?\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2021-05-04T08:35:10+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2021-05-04T08:35:40+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2018\/11\/ayuntamiento-sarriguren-19-egues.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"900\" \/>\r\n\t<meta property=\"og:image:height\" content=\"675\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda\",\"datePublished\":\"2021-05-04T08:35:10+00:00\",\"dateModified\":\"2021-05-04T08:35:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/\"},\"wordCount\":21,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ayuntamiento-sarriguren-19-egues.jpg\",\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/\",\"name\":\"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ayuntamiento-sarriguren-19-egues.jpg\",\"datePublished\":\"2021-05-04T08:35:10+00:00\",\"dateModified\":\"2021-05-04T08:35:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ayuntamiento-sarriguren-19-egues.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2018\\\/11\\\/ayuntamiento-sarriguren-19-egues.jpg\",\"width\":900,\"height\":675,\"caption\":\"ayuntamiento-sarriguren-19-egues\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/","og_locale":"eu_ES","og_type":"article","og_title":"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Osoko bilkura 2021\/05\/04\/ Tamaina : 185.8 kB Formatua : PDFParte-hartu:&iquest;Quieres participar en el Pleno Ordinario? Ohiko Osoko Bilkuran parte hartu nahi duzu?","og_url":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2021-05-04T08:35:10+00:00","article_modified_time":"2021-05-04T08:35:40+00:00","og_image":[{"width":900,"height":675,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2018\/11\/ayuntamiento-sarriguren-19-egues.jpg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda","datePublished":"2021-05-04T08:35:10+00:00","dateModified":"2021-05-04T08:35:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/"},"wordCount":21,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2018\/11\/ayuntamiento-sarriguren-19-egues.jpg","inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/","url":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/","name":"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2018\/11\/ayuntamiento-sarriguren-19-egues.jpg","datePublished":"2021-05-04T08:35:10+00:00","dateModified":"2021-05-04T08:35:40+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2018\/11\/ayuntamiento-sarriguren-19-egues.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2018\/11\/ayuntamiento-sarriguren-19-egues.jpg","width":900,"height":675,"caption":"ayuntamiento-sarriguren-19-egues"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021eko-maiatzaren-4ko-osoko-bilkuraten-deialdia-eta-gai-zerrenda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"2021eko maiatzaren 4ko osoko bilkuraten deialdia eta gai zerrenda"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias\/21947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/5944"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=21947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}