{"id":21409,"date":"2021-03-22T13:20:29","date_gmt":"2021-03-22T12:20:29","guid":{"rendered":"https:\/\/www.valledeegues.com\/?p=21409"},"modified":"2021-03-22T13:29:19","modified_gmt":"2021-03-22T12:29:19","slug":"2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak","status":"publish","type":"noticias","link":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/","title":{"rendered":"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p>Martxoaren 22ko NAOan (64. zk.) argitaratu dira Eguesibarko Udalak kirol-arlotik deitzen dituen laguntzak. Esteka honetan kontsulta daitezke: <a href=\"https:\/\/bon.navarra.es\/eu\/iragarkia\/-\/texto\/2021\/64\/61\">https:\/\/bon.navarra.es\/eu\/iragarkia\/-\/texto\/2021\/64\/61<\/a><\/p><p><strong><a href=\"https:\/\/www.valledeegues.com\/eu\/subvenciones_cpt\/extracto-de-subvenciones-a-clubes-deportivos-que-desarrollen-escuelas-deportivas-en-temporada-deportiva-2021-2022\/\">2021-2022 denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzen deialdiaren laburpena<\/a><\/strong><\/p><p>Edozein zalantza argitzeko, interesdunek honako helbide honen bidez jar daitezke harremanetan deialdia egin duen arloarekin: deporte-kirola@egues.es<\/p>\n","protected":false},"author":2,"featured_media":21424,"template":"","format":"standard","meta":{"_wpml_word_count":["90"],"_edit_lock":["1616416024:2"],"_edit_last":["2"],"_wpml_media_featured":["1"],"_wpml_media_duplicate":["1"],"_wpml_location_migration_done":["1"],"cptr_related":["a:0:{}"],"boxed_layout_shadow_size":["0"],"_yoast_wpseo_content_score":["60"],"_yoast_wpseo_primary_category":["26"],"_thumbnail_id":["21424"],"_wpml_media_has_media":["1"],"_theme_options_build":["696f71999b1ad"]},"class_list":["post-21409","noticias","type-noticias","status-publish","format-standard","has-post-thumbnail","hentry","categorianoticias-albisteak","categorianoticias-kirola-noticias","categorianoticias-udala-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Martxoaren 22ko NAOan (64. zk.) argitaratu dira Eguesibarko Udalak kirol-arlotik deitzen dituen laguntzak. Esteka honetan kontsulta daitezke: https:\/\/bon.navarra.es\/eu\/iragarkia\/-\/texto\/2021\/64\/612021-2022 denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzen deialdiaren laburpenaEdozein zalantza argitzeko, interesdunek honako helbide honen bidez jar daitezke harremanetan deialdia egin duen arloarekin: deporte-kirola@egues.es\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:published_time\" content=\"2021-03-22T12:20:29+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2021-03-22T12:29:19+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/03\/pexels-edgar-colomba-2169302.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\r\n\t<meta property=\"og:image:height\" content=\"981\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"gestionegues\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:creator\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"gestionegues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/\"},\"author\":{\"name\":\"gestionegues\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\"},\"headline\":\"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak\",\"datePublished\":\"2021-03-22T12:20:29+00:00\",\"dateModified\":\"2021-03-22T12:29:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/\"},\"wordCount\":58,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/pexels-edgar-colomba-2169302.jpg\",\"inLanguage\":\"eu-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/\",\"name\":\"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/pexels-edgar-colomba-2169302.jpg\",\"datePublished\":\"2021-03-22T12:20:29+00:00\",\"dateModified\":\"2021-03-22T12:29:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/pexels-edgar-colomba-2169302.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2021\\\/03\\\/pexels-edgar-colomba-2169302.jpg\",\"width\":1500,\"height\":981,\"caption\":\"Pexels Edgar Colomba 2169302\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/noticias\\\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/person\\\/84a1438b4b6b8a26032867ddb04bab2c\",\"name\":\"gestionegues\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g\",\"caption\":\"gestionegues\"},\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/author\\\/gestionegues\\\/\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/","og_locale":"eu_ES","og_type":"article","og_title":"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Martxoaren 22ko NAOan (64. zk.) argitaratu dira Eguesibarko Udalak kirol-arlotik deitzen dituen laguntzak. Esteka honetan kontsulta daitezke: https:\/\/bon.navarra.es\/eu\/iragarkia\/-\/texto\/2021\/64\/612021-2022 denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzen deialdiaren laburpenaEdozein zalantza argitzeko, interesdunek honako helbide honen bidez jar daitezke harremanetan deialdia egin duen arloarekin: deporte-kirola@egues.es","og_url":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_published_time":"2021-03-22T12:20:29+00:00","article_modified_time":"2021-03-22T12:29:19+00:00","og_image":[{"width":1500,"height":981,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/03\/pexels-edgar-colomba-2169302.jpg","type":"image\/jpeg"}],"author":"gestionegues","twitter_card":"summary_large_image","twitter_creator":"@AValledeEgues","twitter_site":"@AValledeEgues","twitter_misc":{"Written by":"gestionegues"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/#article","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/"},"author":{"name":"gestionegues","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c"},"headline":"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak","datePublished":"2021-03-22T12:20:29+00:00","dateModified":"2021-03-22T12:29:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/"},"wordCount":58,"commentCount":0,"publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/03\/pexels-edgar-colomba-2169302.jpg","inLanguage":"eu-ES"},{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/","url":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/","name":"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/03\/pexels-edgar-colomba-2169302.jpg","datePublished":"2021-03-22T12:20:29+00:00","dateModified":"2021-03-22T12:29:19+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/03\/pexels-edgar-colomba-2169302.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2021\/03\/pexels-edgar-colomba-2169302.jpg","width":1500,"height":981,"caption":"Pexels Edgar Colomba 2169302"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/noticias\/2021-2022-kirol-denboraldian-kirol-eskolak-garatzen-dituzten-kirol-klubentzako-diru-laguntzak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"2021-2022 kirol-denboraldian kirol-eskolak garatzen dituzten kirol-klubentzako diru-laguntzak"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]},{"@type":"Person","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/person\/84a1438b4b6b8a26032867ddb04bab2c","name":"gestionegues","image":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d4291e1e6b3080021aaef4cb9ec608c45d6c6f7b59c89ffb94b155303fbe34d9?s=96&d=mm&r=g","caption":"gestionegues"},"url":"https:\/\/www.valledeegues.com\/eu\/author\/gestionegues\/"}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias\/21409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/noticias"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/noticias"}],"author":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/21424"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=21409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}