{"id":47055,"date":"2026-05-07T09:43:55","date_gmt":"2026-05-07T07:43:55","guid":{"rendered":"https:\/\/www.valledeegues.com\/?post_type=eventos&#038;p=47055"},"modified":"2026-05-07T09:49:13","modified_gmt":"2026-05-07T07:49:13","slug":"maskharah-programa-gynkhana-sarrigurengo-aztarnak","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/","title":{"rendered":"MASKHARAH PROGRAMA \u201dGYNKHANA: SARRIGURENGO AZTARNAK\u201d"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Ezagutu herriaren ingurunea bere testura, hiri-elementu eta elementu naturalen bidez. Inguruko hainbat espazioetatik zabiltzaten bitartean, hainbat elementuren aztarnak edo testurak atzemango dituzue, koaderno pertsonal bat egiteko.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"featured_media":47054,"template":"","meta":{"_edit_lock":["1778140025:2"],"_edit_last":["2"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"barra":[""],"dias":[";16-5-2026;"],"event_date":["1778889600"],"event_date1":["1778889600"],"event_horario_fin":[""],"event_horario_inicio":["18:30"],"imagenslia":[""],"autor_o":[""],"boton1":[""],"boton1u":[""],"event_ext":[""],"event_horario":["18:30"],"event_location":["46973"],"fechas":[""],"importe":["Doan"],"inscripcion":[""],"nota":["8-14 urte"],"ponente":[""],"_thumbnail_id":["47054"],"_wpml_word_count":["53"],"botonve":["Izen-ematea"],"botonveu":["https:\/\/inscripciones012.navarra.es\/GN012\/Evento\/7702"],"mostrar_barra":["1"],"_last_translation_edit_mode":["native-editor"]},"class_list":["post-47055","eventos","type-eventos","status-publish","has-post-thumbnail","hentry","categoriaeventos-izen-emateak_eve","categoriaeventos-kultura"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>MASKHARAH PROGRAMA \u201dGYNKHANA: SARRIGURENGO AZTARNAK\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"MASKHARAH PROGRAMA \u201dGYNKHANA: SARRIGURENGO AZTARNAK\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Ezagutu herriaren ingurunea bere testura, hiri-elementu eta elementu naturalen bidez. Inguruko hainbat espazioetatik zabiltzaten bitartean, hainbat elementuren aztarnak edo testurak atzemango dituzue, koaderno pertsonal bat egiteko. &nbsp;\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-05-07T07:49:13+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/Las-huellas-de-Sarriguren.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"385\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\\\/\",\"name\":\"MASKHARAH PROGRAMA \u201dGYNKHANA: SARRIGURENGO AZTARNAK\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Las-huellas-de-Sarriguren.png\",\"datePublished\":\"2026-05-07T07:43:55+00:00\",\"dateModified\":\"2026-05-07T07:49:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Las-huellas-de-Sarriguren.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/Las-huellas-de-Sarriguren.png\",\"width\":800,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ekitaldiak\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MASKHARAH PROGRAMA \u201dGYNKHANA: SARRIGURENGO AZTARNAK\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MASKHARAH PROGRAMA \u201dGYNKHANA: SARRIGURENGO AZTARNAK\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/","og_locale":"eu_ES","og_type":"article","og_title":"MASKHARAH PROGRAMA \u201dGYNKHANA: SARRIGURENGO AZTARNAK\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Ezagutu herriaren ingurunea bere testura, hiri-elementu eta elementu naturalen bidez. Inguruko hainbat espazioetatik zabiltzaten bitartean, hainbat elementuren aztarnak edo testurak atzemango dituzue, koaderno pertsonal bat egiteko. &nbsp;","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_modified_time":"2026-05-07T07:49:13+00:00","og_image":[{"width":800,"height":385,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/Las-huellas-de-Sarriguren.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/","name":"MASKHARAH PROGRAMA \u201dGYNKHANA: SARRIGURENGO AZTARNAK\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/Las-huellas-de-Sarriguren.png","datePublished":"2026-05-07T07:43:55+00:00","dateModified":"2026-05-07T07:49:13+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/Las-huellas-de-Sarriguren.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/Las-huellas-de-Sarriguren.png","width":800,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/maskharah-programa-gynkhana-sarrigurengo-aztarnak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Ekitaldiak","item":"https:\/\/www.valledeegues.com\/eu\/eventos\/"},{"@type":"ListItem","position":3,"name":"MASKHARAH PROGRAMA \u201dGYNKHANA: SARRIGURENGO AZTARNAK\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/47055","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/47054"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=47055"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}