{"id":46683,"date":"2026-05-04T08:40:16","date_gmt":"2026-05-04T06:40:16","guid":{"rendered":"http:\/\/w3.valledeegues.com\/eventos\/rebecos-trail-2026\/"},"modified":"2026-05-04T08:40:59","modified_gmt":"2026-05-04T06:40:59","slug":"rebecos-trail-2026","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/","title":{"rendered":"Rebecos Trail 2026"},"content":{"rendered":"<p>Dagoeneko zabalik dago 2026eko Rebecos Trail izena emateko epea. Proba maiatzaren 24an izango da.<\/p>\n<p>10:00etan abiatuko da Eguesetik eta 2 ibilbide izanen dira:<\/p>\n<ul>\n<li>REBEKITA 11,3 KM eta 428 metroko desnibel positiboa<\/li>\n<li>REBEKO, 18,6 KM eta 682 metroko desnibel positiboa<\/li>\n<\/ul>\n","protected":false},"featured_media":46682,"template":"","meta":{"_wpml_word_count":["42"],"event_ext":[""],"event_location":["46679"],"imagenslia":[""],"event_horario":["10:00"],"event_horario_inicio":["10:00"],"event_horario_fin":[""],"fechas":[""],"importe":[""],"inscripcion":["Informazio guztia eta izen-emateak: https:\/\/www.rebecostrail.com\/"],"botonve":["Izen-ematea"],"botonveu":["https:\/\/www.rebecostrail.com\/"],"ponente":[""],"autor_o":[""],"nota":[""],"boton1":[""],"boton1u":[""],"barra":[""],"mostrar_barra":["1"],"dias":[";24-5-2026;"],"event_date":["1779580800"],"event_date1":["1779580800"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_thumbnail_id":["46682"],"_edit_lock":["1777876876:9"],"_edit_last":["9"],"_last_translation_edit_mode":["native-editor"]},"class_list":["post-46683","eventos","type-eventos","status-publish","has-post-thumbnail","hentry","categoriaeventos-izen-emateak_eve","categoriaeventos-kirolak_eve"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Rebecos Trail 2026 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Rebecos Trail 2026 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Dagoeneko zabalik dago 2026eko Rebecos Trail izena emateko epea. Proba maiatzaren 24an izango da. 10:00etan abiatuko da Eguesetik eta 2 ibilbide izanen dira: REBEKITA 11,3 KM eta 428 metroko desnibel positiboa REBEKO, 18,6 KM eta 682 metroko desnibel positiboa\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-05-04T06:40:59+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/rebecos-trail-agenda.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"894\" \/>\r\n\t<meta property=\"og:image:height\" content=\"403\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/rebecos-trail-2026\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/rebecos-trail-2026\\\/\",\"name\":\"Rebecos Trail 2026 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/rebecos-trail-2026\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/rebecos-trail-2026\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/rebecos-trail-agenda.jpg\",\"datePublished\":\"2026-05-04T06:40:16+00:00\",\"dateModified\":\"2026-05-04T06:40:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/rebecos-trail-2026\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/rebecos-trail-2026\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/rebecos-trail-2026\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/rebecos-trail-agenda.jpg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/rebecos-trail-agenda.jpg\",\"width\":894,\"height\":403},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/rebecos-trail-2026\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ekitaldiak\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rebecos Trail 2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rebecos Trail 2026 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/","og_locale":"eu_ES","og_type":"article","og_title":"Rebecos Trail 2026 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Dagoeneko zabalik dago 2026eko Rebecos Trail izena emateko epea. Proba maiatzaren 24an izango da. 10:00etan abiatuko da Eguesetik eta 2 ibilbide izanen dira: REBEKITA 11,3 KM eta 428 metroko desnibel positiboa REBEKO, 18,6 KM eta 682 metroko desnibel positiboa","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_modified_time":"2026-05-04T06:40:59+00:00","og_image":[{"width":894,"height":403,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/rebecos-trail-agenda.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/","name":"Rebecos Trail 2026 - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/rebecos-trail-agenda.jpg","datePublished":"2026-05-04T06:40:16+00:00","dateModified":"2026-05-04T06:40:59+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/rebecos-trail-agenda.jpg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/05\/rebecos-trail-agenda.jpg","width":894,"height":403},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/rebecos-trail-2026\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Ekitaldiak","item":"https:\/\/www.valledeegues.com\/eu\/eventos\/"},{"@type":"ListItem","position":3,"name":"Rebecos Trail 2026"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/46683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/46682"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=46683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}