{"id":45018,"date":"2026-03-02T10:40:11","date_gmt":"2026-03-02T09:40:11","guid":{"rendered":"https:\/\/www.valledeegues.com\/evento\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/"},"modified":"2026-03-02T10:40:11","modified_gmt":"2026-03-02T09:40:11","slug":"arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/","title":{"rendered":"ARTE ESZENIKOEN HAUR PROGRAMA: &#8220;VENUS Y MARTE: LA MAGIA ENTRE DOS MENTES&#8221;"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p>Magia ikuskizun honetan trikimailu ikaragarriak, memoria jokoak eta hipnosi pixka bat ere erabiliko ditugu aho zabalik uzteko. Oso ikuskizun dibertigarria izango da, barre eta sorpresaz betea, eta bertan ikasiko dugu zergatik garen garen bezalakoak, pila bat dibertitzen garen bitartean. Ez da magia normala, gure bihotza eta burua ulertzeko magia baizik.  <\/p><p>Adina: + 4 urte<br>\n&#128467;&#65039;martxoak 8<br>\n&#128347;12:00<br>\n&#128205;Institutuko gimnasioa<br>\n&#9997;&#127997; Izen-emateak: <a href=\"https:\/\/inscripciones012.navarra.es\/GN012\/Evento\/7314\" target=\"_blank\" rel=\"noopener\">https:\/\/inscripciones012.navarra.es\/GN012\/Evento\/7314<\/a><\/p><p>&nbsp;<\/p>\n","protected":false},"featured_media":45017,"template":"","meta":{"_tribe_modified_fields":["a:22:{s:14:\"_alp_processed\";i:1772448256;s:12:\"_EventOrigin\";i:1772448256;s:17:\"_EventShowMapLink\";i:1772448256;s:13:\"_EventShowMap\";i:1772448256;s:13:\"_EventVenueID\";i:1772448256;s:15:\"_EventStartDate\";i:1772448256;s:13:\"_EventEndDate\";i:1772448256;s:18:\"_EventStartDateUTC\";i:1772448256;s:16:\"_EventEndDateUTC\";i:1772448256;s:14:\"_EventDuration\";i:1772448256;s:14:\"_EventTimezone\";i:1772448256;s:18:\"_EventTimezoneAbbr\";i:1772448256;s:16:\"_EventRecurrence\";i:1772448256;s:21:\"_wpml_media_duplicate\";i:1772448256;s:20:\"_wpml_media_featured\";i:1772448256;s:17:\"_top_nav_excluded\";i:1772448256;s:17:\"_cms_nav_minihome\";i:1772448256;s:13:\"_thumbnail_id\";i:1772448256;s:27:\"_last_translation_edit_mode\";i:1772448256;s:16:\"_wpml_word_count\";i:1772448257;s:15:\"_dynamic_styles\";i:1772448310;s:20:\"_theme_options_build\";i:1772448310;}"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_top_nav_excluded":[""],"_cms_nav_minihome":[""],"_thumbnail_id":["45017"],"_last_translation_edit_mode":["translation-editor"],"_wpml_word_count":["98"],"_theme_options_build":["696f71999b1ad"],"event_ext":["Gimnasio Instituto Sarriguren"],"event_location":["44129"],"event_horario_inicio":["12:00"],"event_horario_fin":["12:00"],"event_horario":["12:00 - 12:00"],"dias":[";8-3-2026;"],"event_date":["1772971200"],"event_date1":["1772971200"]},"class_list":["post-45018","eventos","type-eventos","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>ARTE ESZENIKOEN HAUR PROGRAMA: &quot;VENUS Y MARTE: LA MAGIA ENTRE DOS MENTES&quot; - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"ARTE ESZENIKOEN HAUR PROGRAMA: &quot;VENUS Y MARTE: LA MAGIA ENTRE DOS MENTES&quot; - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Magia ikuskizun honetan trikimailu ikaragarriak, memoria jokoak eta hipnosi pixka bat ere erabiliko ditugu aho zabalik uzteko. Oso ikuskizun dibertigarria izango da, barre eta sorpresaz betea, eta bertan ikasiko dugu zergatik garen garen bezalakoak, pila bat dibertitzen garen bitartean. Ez da magia normala, gure bihotza eta burua ulertzeko magia baizik. Adina: + 4 urte &#128467;&#65039;martxoak [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/03\/magia-agenda.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"385\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\\\/\",\"name\":\"ARTE ESZENIKOEN HAUR PROGRAMA: \\\"VENUS Y MARTE: LA MAGIA ENTRE DOS MENTES\\\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/magia-agenda.png\",\"datePublished\":\"2026-03-02T09:40:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/magia-agenda.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/magia-agenda.png\",\"width\":800,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ekitaldiak\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ARTE ESZENIKOEN HAUR PROGRAMA: &#8220;VENUS Y MARTE: LA MAGIA ENTRE DOS MENTES&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARTE ESZENIKOEN HAUR PROGRAMA: \"VENUS Y MARTE: LA MAGIA ENTRE DOS MENTES\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/","og_locale":"eu_ES","og_type":"article","og_title":"ARTE ESZENIKOEN HAUR PROGRAMA: \"VENUS Y MARTE: LA MAGIA ENTRE DOS MENTES\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Magia ikuskizun honetan trikimailu ikaragarriak, memoria jokoak eta hipnosi pixka bat ere erabiliko ditugu aho zabalik uzteko. Oso ikuskizun dibertigarria izango da, barre eta sorpresaz betea, eta bertan ikasiko dugu zergatik garen garen bezalakoak, pila bat dibertitzen garen bitartean. Ez da magia normala, gure bihotza eta burua ulertzeko magia baizik. Adina: + 4 urte &#128467;&#65039;martxoak [&hellip;]","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","og_image":[{"width":800,"height":385,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/03\/magia-agenda.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/","name":"ARTE ESZENIKOEN HAUR PROGRAMA: \"VENUS Y MARTE: LA MAGIA ENTRE DOS MENTES\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/03\/magia-agenda.png","datePublished":"2026-03-02T09:40:11+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/03\/magia-agenda.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/03\/magia-agenda.png","width":800,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-venus-y-marte-la-magia-entre-dos-mentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Ekitaldiak","item":"https:\/\/www.valledeegues.com\/eu\/eventos\/"},{"@type":"ListItem","position":3,"name":"ARTE ESZENIKOEN HAUR PROGRAMA: &#8220;VENUS Y MARTE: LA MAGIA ENTRE DOS MENTES&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/45018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/45017"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=45018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}