{"id":44621,"date":"2026-02-13T13:03:37","date_gmt":"2026-02-13T12:03:37","guid":{"rendered":"https:\/\/www.valledeegues.com\/evento\/arte-eszenikoen-haur-programa-azken-fakirra\/"},"modified":"2026-02-13T13:03:37","modified_gmt":"2026-02-13T12:03:37","slug":"arte-eszenikoen-haur-programa-azken-fakirra","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/","title":{"rendered":"ARTE ESZENIKOEN HAUR PROGRAMA: &#8220;AZKEN FAKIRRA&#8221;"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p>Sir Imiri Fakir Handiak bere azken eginkizunei aurre egin behar die erretiroa hartu aurretik. Bera izango al da azken fakirra edo edozein objektu zorrotzi erabateko fobia dion ilobak aurre egingo ote die bere beldurrei? <\/p><p>Zirika Zirkus<\/p><p>Euskaraz<\/p><p>&#128467;&#65039; otsailak 22 d<\/p><p>&#128347; 12:00<\/p><p>&#128205;Institutuko gimnasioa<\/p><p>&#9997;&#127997; Izen- emateak: <a href=\"https:\/\/inscripciones012.navarra.es\/GN012\/Evento\/7314\" target=\"_blank\" rel=\"noopener\">https:\/\/inscripciones012.navarra.es\/GN012\/Evento\/7314<\/a><\/p>\n","protected":false},"featured_media":44619,"template":"","meta":{"_tribe_modified_fields":["a:23:{s:14:\"_alp_processed\";i:1770999255;s:12:\"_EventOrigin\";i:1770999255;s:17:\"_EventShowMapLink\";i:1770999255;s:13:\"_EventShowMap\";i:1770999255;s:13:\"_EventVenueID\";i:1770999255;s:15:\"_EventStartDate\";i:1770999255;s:13:\"_EventEndDate\";i:1770999255;s:18:\"_EventStartDateUTC\";i:1770999255;s:16:\"_EventEndDateUTC\";i:1770999268;s:14:\"_EventDuration\";i:1770999255;s:14:\"_EventTimezone\";i:1770999255;s:18:\"_EventTimezoneAbbr\";i:1770999255;s:16:\"_EventRecurrence\";i:1770999255;s:21:\"_wpml_media_duplicate\";i:1770999255;s:20:\"_wpml_media_featured\";i:1770999255;s:17:\"_top_nav_excluded\";i:1770999268;s:17:\"_cms_nav_minihome\";i:1770999268;s:16:\"tribe_events_cat\";i:1770995655;s:13:\"_thumbnail_id\";i:1770999255;s:27:\"_last_translation_edit_mode\";i:1770999255;s:16:\"_wpml_word_count\";i:1770999255;s:15:\"_dynamic_styles\";i:1770999409;s:20:\"_theme_options_build\";i:1770999409;}"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_thumbnail_id":["44619"],"_last_translation_edit_mode":["translation-editor"],"_wpml_word_count":["71"],"_theme_options_build":["696f71999b1ad"],"event_ext":["Gimnasio Instituto Sarriguren"],"event_location":["44129"],"event_horario_inicio":["12:00"],"event_horario_fin":["12:00"],"event_horario":["12:00 - 12:00"],"dias":[";22-2-2026;"],"event_date":["1771761600"],"event_date1":["1771761600"]},"class_list":["post-44621","eventos","type-eventos","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>ARTE ESZENIKOEN HAUR PROGRAMA: &quot;AZKEN FAKIRRA&quot; - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"ARTE ESZENIKOEN HAUR PROGRAMA: &quot;AZKEN FAKIRRA&quot; - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Sir Imiri Fakir Handiak bere azken eginkizunei aurre egin behar die erretiroa hartu aurretik. Bera izango al da azken fakirra edo edozein objektu zorrotzi erabateko fobia dion ilobak aurre egingo ote die bere beldurrei? Zirika ZirkusEuskaraz&#128467;&#65039; otsailak 22 d&#128347; 12:00&#128205;Institutuko gimnasioa&#9997;&#127997; Izen- emateak: https:\/\/inscripciones012.navarra.es\/GN012\/Evento\/7314\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/02\/azken-fakirra-agenda.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"385\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-azken-fakirra\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-azken-fakirra\\\/\",\"name\":\"ARTE ESZENIKOEN HAUR PROGRAMA: \\\"AZKEN FAKIRRA\\\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-azken-fakirra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-azken-fakirra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/azken-fakirra-agenda.png\",\"datePublished\":\"2026-02-13T12:03:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-azken-fakirra\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-azken-fakirra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-azken-fakirra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/azken-fakirra-agenda.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/azken-fakirra-agenda.png\",\"width\":800,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-azken-fakirra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ekitaldiak\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ARTE ESZENIKOEN HAUR PROGRAMA: &#8220;AZKEN FAKIRRA&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARTE ESZENIKOEN HAUR PROGRAMA: \"AZKEN FAKIRRA\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/","og_locale":"eu_ES","og_type":"article","og_title":"ARTE ESZENIKOEN HAUR PROGRAMA: \"AZKEN FAKIRRA\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Sir Imiri Fakir Handiak bere azken eginkizunei aurre egin behar die erretiroa hartu aurretik. Bera izango al da azken fakirra edo edozein objektu zorrotzi erabateko fobia dion ilobak aurre egingo ote die bere beldurrei? Zirika ZirkusEuskaraz&#128467;&#65039; otsailak 22 d&#128347; 12:00&#128205;Institutuko gimnasioa&#9997;&#127997; Izen- emateak: https:\/\/inscripciones012.navarra.es\/GN012\/Evento\/7314","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","og_image":[{"width":800,"height":385,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/02\/azken-fakirra-agenda.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/","name":"ARTE ESZENIKOEN HAUR PROGRAMA: \"AZKEN FAKIRRA\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/02\/azken-fakirra-agenda.png","datePublished":"2026-02-13T12:03:37+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/02\/azken-fakirra-agenda.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/02\/azken-fakirra-agenda.png","width":800,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-azken-fakirra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Ekitaldiak","item":"https:\/\/www.valledeegues.com\/eu\/eventos\/"},{"@type":"ListItem","position":3,"name":"ARTE ESZENIKOEN HAUR PROGRAMA: &#8220;AZKEN FAKIRRA&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/44621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/44619"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=44621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}