{"id":44138,"date":"2026-01-28T08:45:10","date_gmt":"2026-01-28T07:45:10","guid":{"rendered":"https:\/\/www.valledeegues.com\/?post_type=tribe_events&#038;p=44138"},"modified":"2026-01-28T09:00:54","modified_gmt":"2026-01-28T08:00:54","slug":"arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/","title":{"rendered":"Arte eszenikoen haur programa: &#8220;Guille y el mordisco del vampiro&#8221;"},"content":{"rendered":"<?xml encoding=\"utf-8\" ?><p>Colectivo Humoren txotxongilo antzerkirako izena emateko epea irekia.<\/p><p>Guillek eta Pancetok, bere txakurrak, banpiro arraro samarra aurkitu dute: marrubi zukuak nahiago ditu giza odola baino. Eta, beldur handirik ematen ez duen arren, tematu egin da Guilleren jugularrari kosk egiten eta &ldquo;benetako banpiroa&rdquo; izaten, aitak dioen bezala.<\/p><p>Adina: +3 urte<\/p><p>&#128467;&#65039; Otsailak 8<\/p><p>&#128347; 12:00<\/p><p>&#128205; Sarrigurengo Institutuko Gimnasioa<\/p><p>&#127903;&#65039; Edukiera mugatua. Lehentasuna erroldatuak, ez erroldatuak itxaron zerrendan. Lekua izan zein ez, jakinarazi egingo da.<\/p><p>&#9997;&#127997; Izen-ematea emanaldiaren aurreko asteazkenera arte: <a href=\"https:\/\/inscripciones012.navarra.es\/GN012\/Evento\/7314\" target=\"_blank\" rel=\"noopener\">https:\/\/inscripciones012.navarra.es\/GN012\/Evento\/7314<\/a><\/p>\n","protected":false},"featured_media":44125,"template":"","meta":{"_tribe_modified_fields":["a:32:{s:12:\"_EventOrigin\";i:1769589933;s:10:\"_edit_last\";i:1769589998;s:10:\"post_title\";i:1769590020;s:11:\"post_status\";i:1769590424;s:17:\"_EventShowMapLink\";i:1769590424;s:13:\"_EventShowMap\";i:1769589998;s:13:\"_EventVenueID\";i:1769590424;s:15:\"_EventStartDate\";i:1769589998;s:13:\"_EventEndDate\";i:1769589998;s:18:\"_EventStartDateUTC\";i:1769589998;s:16:\"_EventEndDateUTC\";i:1769589998;s:14:\"_EventDuration\";i:1769589998;s:14:\"_EventTimezone\";i:1769589998;s:18:\"_EventTimezoneAbbr\";i:1769589998;s:16:\"_EventRecurrence\";i:1769589998;s:21:\"_wpml_media_duplicate\";i:1769589998;s:20:\"_wpml_media_featured\";i:1769589998;s:13:\"_thumbnail_id\";i:1769589998;s:14:\"_alp_processed\";i:1769590854;s:16:\"_wpml_word_count\";i:1769590288;s:12:\"post_content\";i:1769590800;s:16:\"tribe_events_cat\";i:1769586763;s:12:\"cptr_related\";i:1769590363;s:20:\"_EventCurrencySymbol\";i:1769590363;s:18:\"_EventCurrencyCode\";i:1769590363;s:22:\"_EventCurrencyPosition\";i:1769590363;s:10:\"_EventCost\";i:1769590363;s:9:\"_EventURL\";i:1769590363;s:27:\"_last_translation_edit_mode\";i:1769590364;s:15:\"_dynamic_styles\";i:1769590366;s:20:\"_theme_options_build\";i:1769590366;s:21:\"_wpml_media_has_media\";i:1769590854;}"],"_edit_lock":["1769587199:8"],"_edit_last":["8"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_thumbnail_id":["44125"],"_wpml_word_count":["125"],"cptr_related":["a:0:{}"],"_last_translation_edit_mode":["native-editor"],"_theme_options_build":["696f71999b1ad"],"_wpml_media_has_media":["1"],"event_ext":["Gimnasio Instituto Sarriguren"],"event_location":["44129"],"event_horario_inicio":["12:00"],"event_horario_fin":["13:00"],"event_horario":["12:00 - 13:00"],"dias":[";8-2-2026;"],"event_date":["1770552000"],"event_date1":["1770555600"]},"class_list":["post-44138","eventos","type-eventos","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Arte eszenikoen haur programa: &quot;Guille y el mordisco del vampiro&quot; - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Arte eszenikoen haur programa: &quot;Guille y el mordisco del vampiro&quot; - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Colectivo Humoren txotxongilo antzerkirako izena emateko epea irekia.Guillek eta Pancetok, bere txakurrak, banpiro arraro samarra aurkitu dute: marrubi zukuak nahiago ditu giza odola baino. Eta, beldur handirik ematen ez duen arren, tematu egin da Guilleren jugularrari kosk egiten eta &ldquo;benetako banpiroa&rdquo; izaten, aitak dioen bezala.Adina: +3 urte&#128467;&#65039; Otsailak 8&#128347; 12:00&#128205; Sarrigurengo Institutuko Gimnasioa&#127903;&#65039; Edukiera mugatua. [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-01-28T08:00:54+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/01\/agenda-teatro-5.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"385\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\\\/\",\"name\":\"Arte eszenikoen haur programa: \\\"Guille y el mordisco del vampiro\\\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/agenda-teatro-5.png\",\"datePublished\":\"2026-01-28T07:45:10+00:00\",\"dateModified\":\"2026-01-28T08:00:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/agenda-teatro-5.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/agenda-teatro-5.png\",\"width\":800,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ekitaldiak\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arte eszenikoen haur programa: &#8220;Guille y el mordisco del vampiro&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arte eszenikoen haur programa: \"Guille y el mordisco del vampiro\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/","og_locale":"eu_ES","og_type":"article","og_title":"Arte eszenikoen haur programa: \"Guille y el mordisco del vampiro\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Colectivo Humoren txotxongilo antzerkirako izena emateko epea irekia.Guillek eta Pancetok, bere txakurrak, banpiro arraro samarra aurkitu dute: marrubi zukuak nahiago ditu giza odola baino. Eta, beldur handirik ematen ez duen arren, tematu egin da Guilleren jugularrari kosk egiten eta &ldquo;benetako banpiroa&rdquo; izaten, aitak dioen bezala.Adina: +3 urte&#128467;&#65039; Otsailak 8&#128347; 12:00&#128205; Sarrigurengo Institutuko Gimnasioa&#127903;&#65039; Edukiera mugatua. [&hellip;]","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_modified_time":"2026-01-28T08:00:54+00:00","og_image":[{"width":800,"height":385,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/01\/agenda-teatro-5.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/","name":"Arte eszenikoen haur programa: \"Guille y el mordisco del vampiro\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/01\/agenda-teatro-5.png","datePublished":"2026-01-28T07:45:10+00:00","dateModified":"2026-01-28T08:00:54+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/01\/agenda-teatro-5.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2026\/01\/agenda-teatro-5.png","width":800,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/arte-eszenikoen-haur-programa-guille-y-el-mordisco-del-vampiro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Ekitaldiak","item":"https:\/\/www.valledeegues.com\/eu\/eventos\/"},{"@type":"ListItem","position":3,"name":"Arte eszenikoen haur programa: &#8220;Guille y el mordisco del vampiro&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/44138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/44125"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=44138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}