{"id":42284,"date":"2025-11-14T08:47:43","date_gmt":"2025-11-14T07:47:43","guid":{"rendered":"https:\/\/www.valledeegues.com\/evento\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/"},"modified":"2025-11-14T08:55:39","modified_gmt":"2025-11-14T07:55:39","slug":"lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/","title":{"rendered":"LEHEN SAIOA ZINE-KLUBA \u201cGRU: NIRE GUSTOKOEN DOILORRA\u201d"},"content":{"rendered":"<p>Gru gizon deitoragarria da, historia osoko ekintza kriminalik sinestezinena prestatzen ari dena: Ilargia lapurtzea. Bere ama gaiztoak bultzatuta, oztopo bakarra aurki tuko du bidean: hiru neska umezurtz, aldi baterako zaindu beharko dituenak. <\/p>\n<p>7 eta 13 urte bitartekoentzat<\/p>\n<p>\ud83d\uddd3\ufe0f azaroak 23<br \/>\n\ud83d\udd5b17:30<br \/>\n\ud83d\udccdOihanburu aretoa<\/p>\n<p>Sarrera librea, edukiera bete arte<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-42287\" src=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/11\/cine_gru_23_nov-208x300.jpg\" alt=\"\" width=\"208\" height=\"300\" srcset=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/11\/cine_gru_23_nov-208x300.jpg 208w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/11\/cine_gru_23_nov.jpg 279w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/><\/p>\n","protected":false},"featured_media":42282,"template":"","meta":{"_tribe_modified_fields":["a:29:{s:14:\"_alp_processed\";i:1763110539;s:12:\"_EventOrigin\";i:1763110222;s:17:\"_EventShowMapLink\";i:1763110222;s:13:\"_EventShowMap\";i:1763110222;s:13:\"_EventVenueID\";i:1763110222;s:15:\"_EventStartDate\";i:1763110222;s:13:\"_EventEndDate\";i:1763110222;s:18:\"_EventStartDateUTC\";i:1763110222;s:16:\"_EventEndDateUTC\";i:1763110234;s:14:\"_EventDuration\";i:1763110222;s:14:\"_EventTimezone\";i:1763110222;s:18:\"_EventTimezoneAbbr\";i:1763110222;s:16:\"_EventRecurrence\";i:1763110222;s:21:\"_wpml_media_duplicate\";i:1763110222;s:20:\"_wpml_media_featured\";i:1763110222;s:17:\"_top_nav_excluded\";i:1763110560;s:17:\"_cms_nav_minihome\";i:1763110560;s:16:\"tribe_events_cat\";i:1763106622;s:13:\"_thumbnail_id\";i:1763110222;s:27:\"_last_translation_edit_mode\";i:1763110222;s:16:\"_wpml_word_count\";i:1763110223;s:15:\"_dynamic_styles\";i:1763110456;s:20:\"_theme_options_build\";i:1769005356;s:12:\"post_content\";i:1763110539;s:40:\"_oembed_1b7c1c0b03bd68b690a6c264613cb20a\";i:1763129730;s:40:\"_oembed_22f63a27527ff27b0f96dd7008e42f3f\";i:1763129735;s:40:\"_oembed_f2a30cbef803715e166f425181efeaac\";i:1763130754;s:40:\"_oembed_cea615d7a3be58e90dd93d0b54b846b4\";i:1763263599;s:45:\"_oembed_time_cea615d7a3be58e90dd93d0b54b846b4\";i:1763263599;}"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_thumbnail_id":["42282"],"_last_translation_edit_mode":["translation-editor"],"_wpml_word_count":["70"],"_theme_options_build":["696f71999b1ad"],"_oembed_1b7c1c0b03bd68b690a6c264613cb20a":["{{unknown}}"],"_oembed_22f63a27527ff27b0f96dd7008e42f3f":["{{unknown}}"],"_oembed_f2a30cbef803715e166f425181efeaac":["{{unknown}}"],"_oembed_cea615d7a3be58e90dd93d0b54b846b4":["<iframe title=\"Mi nombre es Harvey Milk - Trailer espa\u00f1ol\" width=\"1140\" height=\"641\" src=\"https:\/\/www.youtube.com\/embed\/3uI5o8THOzg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_cea615d7a3be58e90dd93d0b54b846b4":["1763259999"],"event_ext":["Sala Oihanburu"],"event_location":["33270"],"event_horario_inicio":["17:30"],"event_horario_fin":["17:30"],"event_horario":["17:30 - 17:30"],"dias":[";23-11-2025;"],"event_date":["1763919000"],"event_date1":["1763919000"]},"class_list":["post-42284","eventos","type-eventos","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>LEHEN SAIOA ZINE-KLUBA \u201cGRU: NIRE GUSTOKOEN DOILORRA\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"LEHEN SAIOA ZINE-KLUBA \u201cGRU: NIRE GUSTOKOEN DOILORRA\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Gru gizon deitoragarria da, historia osoko ekintza kriminalik sinestezinena prestatzen ari dena: Ilargia lapurtzea. Bere ama gaiztoak bultzatuta, oztopo bakarra aurki tuko du bidean: hiru neska umezurtz, aldi baterako zaindu beharko dituenak. 7 eta 13 urte bitartekoentzat \ud83d\uddd3\ufe0f azaroak 23 \ud83d\udd5b17:30 \ud83d\udccdOihanburu aretoa Sarrera librea, edukiera bete arte\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-11-14T07:55:39+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/11\/cine-club_23_nov-agenda.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"385\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\\\/\",\"name\":\"LEHEN SAIOA ZINE-KLUBA \u201cGRU: NIRE GUSTOKOEN DOILORRA\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cine-club_23_nov-agenda.png\",\"datePublished\":\"2025-11-14T07:47:43+00:00\",\"dateModified\":\"2025-11-14T07:55:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cine-club_23_nov-agenda.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/cine-club_23_nov-agenda.png\",\"width\":800,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LEHEN SAIOA ZINE-KLUBA \u201cGRU: NIRE GUSTOKOEN DOILORRA\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LEHEN SAIOA ZINE-KLUBA \u201cGRU: NIRE GUSTOKOEN DOILORRA\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/","og_locale":"eu_ES","og_type":"article","og_title":"LEHEN SAIOA ZINE-KLUBA \u201cGRU: NIRE GUSTOKOEN DOILORRA\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Gru gizon deitoragarria da, historia osoko ekintza kriminalik sinestezinena prestatzen ari dena: Ilargia lapurtzea. Bere ama gaiztoak bultzatuta, oztopo bakarra aurki tuko du bidean: hiru neska umezurtz, aldi baterako zaindu beharko dituenak. 7 eta 13 urte bitartekoentzat \ud83d\uddd3\ufe0f azaroak 23 \ud83d\udd5b17:30 \ud83d\udccdOihanburu aretoa Sarrera librea, edukiera bete arte","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_modified_time":"2025-11-14T07:55:39+00:00","og_image":[{"width":800,"height":385,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/11\/cine-club_23_nov-agenda.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/","name":"LEHEN SAIOA ZINE-KLUBA \u201cGRU: NIRE GUSTOKOEN DOILORRA\u201d - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/11\/cine-club_23_nov-agenda.png","datePublished":"2025-11-14T07:47:43+00:00","dateModified":"2025-11-14T07:55:39+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/11\/cine-club_23_nov-agenda.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/11\/cine-club_23_nov-agenda.png","width":800,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/lehen-saioa-zine-kluba-gru-nire-gustokoen-doilorra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"LEHEN SAIOA ZINE-KLUBA \u201cGRU: NIRE GUSTOKOEN DOILORRA\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/42284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/42282"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=42284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}