{"id":41847,"date":"2025-10-30T14:45:13","date_gmt":"2025-10-30T13:45:13","guid":{"rendered":"https:\/\/www.valledeegues.com\/evento\/sare-sozialek-ez-zaitzatela-kontrolatu\/"},"modified":"2025-10-30T14:45:13","modified_gmt":"2025-10-30T13:45:13","slug":"sare-sozialek-ez-zaitzatela-kontrolatu","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/","title":{"rendered":"SARE SOZIALEK EZ ZAITZATELA KONTROLATU"},"content":{"rendered":"<p>Sare sozialak egunero erabiltzen dituzu? Hitzaldi honetan, beti ikusten ez denari buruz hitz egingo dugu zurekin: like-en presioa, zure autoestimuari eragiten dioten alderaketak, ziberjazarpenaren arriskua edo zure pribatutasunaren kontrola galtzea. Sareek zu kontrolatu gabe modu seguruan erabiltzeko gakoak ere emango dizkizugu.  <\/p>\n<p>\ud83d\udc67\ud83e\uddd1Nerabeentzat<\/p>\n<p>\ud83d\uddd3\ufe0fazaroak 4<\/p>\n<p>\ud83d\udd5b 16:30<\/p>\n<p>\ud83d\udccdGazteriaren etxea<\/p>\n<p>\ud83c\udf9f\ufe0f Sarrera librea, edukiera bete arte<\/p>\n","protected":false},"featured_media":41845,"template":"","meta":{"_tribe_modified_fields":["a:25:{s:14:\"_alp_processed\";i:1761835637;s:12:\"_EventOrigin\";i:1761835637;s:17:\"_EventShowMapLink\";i:1761835637;s:13:\"_EventShowMap\";i:1761835637;s:13:\"_EventVenueID\";i:1761835637;s:15:\"_EventStartDate\";i:1761835637;s:13:\"_EventEndDate\";i:1761835637;s:18:\"_EventStartDateUTC\";i:1761835637;s:16:\"_EventEndDateUTC\";i:1761835645;s:14:\"_EventDuration\";i:1761835637;s:14:\"_EventTimezone\";i:1761835637;s:18:\"_EventTimezoneAbbr\";i:1761835637;s:16:\"_EventRecurrence\";i:1761835637;s:21:\"_wpml_media_duplicate\";i:1761835637;s:20:\"_wpml_media_featured\";i:1761835637;s:17:\"_top_nav_excluded\";i:1761835645;s:17:\"_cms_nav_minihome\";i:1761835645;s:16:\"tribe_events_cat\";i:1761832037;s:13:\"_thumbnail_id\";i:1761835637;s:27:\"_last_translation_edit_mode\";i:1761835637;s:16:\"_wpml_word_count\";i:1761835638;s:15:\"_dynamic_styles\";i:1762026282;s:20:\"_theme_options_build\";i:1768957685;s:40:\"_oembed_cea615d7a3be58e90dd93d0b54b846b4\";i:1761864149;s:45:\"_oembed_time_cea615d7a3be58e90dd93d0b54b846b4\";i:1761864149;}"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_thumbnail_id":["41845"],"_last_translation_edit_mode":["translation-editor"],"_wpml_word_count":["84"],"_theme_options_build":["696f71999b1ad"],"_oembed_cea615d7a3be58e90dd93d0b54b846b4":["<iframe title=\"Mi nombre es Harvey Milk - Trailer espa\u00f1ol\" width=\"1140\" height=\"641\" src=\"https:\/\/www.youtube.com\/embed\/3uI5o8THOzg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_cea615d7a3be58e90dd93d0b54b846b4":["1761860549"],"event_ext":["Casa de la juventud"],"event_location":["38316"],"event_horario_inicio":["16:30"],"event_horario_fin":["16:30"],"event_horario":["16:30 - 16:30"],"dias":[";4-11-2025;"],"event_date":["1762273800"],"event_date1":["1762273800"]},"class_list":["post-41847","eventos","type-eventos","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>SARE SOZIALEK EZ ZAITZATELA KONTROLATU - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"SARE SOZIALEK EZ ZAITZATELA KONTROLATU - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Sare sozialak egunero erabiltzen dituzu? Hitzaldi honetan, beti ikusten ez denari buruz hitz egingo dugu zurekin: like-en presioa, zure autoestimuari eragiten dioten alderaketak, ziberjazarpenaren arriskua edo zure pribatutasunaren kontrola galtzea. Sareek zu kontrolatu gabe modu seguruan erabiltzeko gakoak ere emango dizkizugu. \ud83d\udc67\ud83e\uddd1Nerabeentzat \ud83d\uddd3\ufe0fazaroak 4 \ud83d\udd5b 16:30 \ud83d\udccdGazteriaren etxea \ud83c\udf9f\ufe0f Sarrera librea, edukiera bete arte\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/que-las-redes-sociales-no-te-controlen-agenda.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"800\" \/>\r\n\t<meta property=\"og:image:height\" content=\"385\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/sare-sozialek-ez-zaitzatela-kontrolatu\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/sare-sozialek-ez-zaitzatela-kontrolatu\\\/\",\"name\":\"SARE SOZIALEK EZ ZAITZATELA KONTROLATU - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/sare-sozialek-ez-zaitzatela-kontrolatu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/sare-sozialek-ez-zaitzatela-kontrolatu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/que-las-redes-sociales-no-te-controlen-agenda.png\",\"datePublished\":\"2025-10-30T13:45:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/sare-sozialek-ez-zaitzatela-kontrolatu\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/sare-sozialek-ez-zaitzatela-kontrolatu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/sare-sozialek-ez-zaitzatela-kontrolatu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/que-las-redes-sociales-no-te-controlen-agenda.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/que-las-redes-sociales-no-te-controlen-agenda.png\",\"width\":800,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/sare-sozialek-ez-zaitzatela-kontrolatu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SARE SOZIALEK EZ ZAITZATELA KONTROLATU\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SARE SOZIALEK EZ ZAITZATELA KONTROLATU - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/","og_locale":"eu_ES","og_type":"article","og_title":"SARE SOZIALEK EZ ZAITZATELA KONTROLATU - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Sare sozialak egunero erabiltzen dituzu? Hitzaldi honetan, beti ikusten ez denari buruz hitz egingo dugu zurekin: like-en presioa, zure autoestimuari eragiten dioten alderaketak, ziberjazarpenaren arriskua edo zure pribatutasunaren kontrola galtzea. Sareek zu kontrolatu gabe modu seguruan erabiltzeko gakoak ere emango dizkizugu. \ud83d\udc67\ud83e\uddd1Nerabeentzat \ud83d\uddd3\ufe0fazaroak 4 \ud83d\udd5b 16:30 \ud83d\udccdGazteriaren etxea \ud83c\udf9f\ufe0f Sarrera librea, edukiera bete arte","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","og_image":[{"width":800,"height":385,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/que-las-redes-sociales-no-te-controlen-agenda.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/","name":"SARE SOZIALEK EZ ZAITZATELA KONTROLATU - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/que-las-redes-sociales-no-te-controlen-agenda.png","datePublished":"2025-10-30T13:45:13+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/que-las-redes-sociales-no-te-controlen-agenda.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/que-las-redes-sociales-no-te-controlen-agenda.png","width":800,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/sare-sozialek-ez-zaitzatela-kontrolatu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"SARE SOZIALEK EZ ZAITZATELA KONTROLATU"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/41847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/41845"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=41847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}