{"id":41088,"date":"2025-10-02T13:59:39","date_gmt":"2025-10-02T11:59:39","guid":{"rendered":"https:\/\/www.valledeegues.com\/evento\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/"},"modified":"2025-10-02T13:59:39","modified_gmt":"2025-10-02T11:59:39","slug":"zine-kluba-lehen-saioa-el-diario-de-greg-2","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/","title":{"rendered":"Zine-Kluba. Lehen saioa: &#8220;El Diario de Greg 2&#8221;"},"content":{"rendered":"<p class=\"x_MsoNormal\" data-olk-copy-source=\"MessageBody\">\u201cEl Diario de Greg 2: Carretera y manta\u201d filma proiektatuko da.<\/p>\n<p class=\"x_MsoNormal\">7 eta 13 urte bitarteko ikusleentzat<\/p>\n<p class=\"x_MsoNormal\">\ud83d\uddd3\ufe0f 2025\/10\/12<\/p>\n<p>\ud83d\udd5b17:30<\/p>\n<p class=\"x_MsoNormal\">\ud83d\udccd Oihanburu aretoa (Sarriguren)<\/p>\n<p class=\"x_MsoNormal\"> Ez da aldez aurretik izena eman behar<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-41081\" src=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-213x300.png\" alt=\"\" width=\"213\" height=\"300\" srcset=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-213x300.png 213w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-726x1024.png 726w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-768x1083.png 768w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-1090x1536.png 1090w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct.png 1240w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-41083\" src=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine_diariogreg_12_oct-208x300.jpg\" alt=\"\" width=\"208\" height=\"300\" srcset=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine_diariogreg_12_oct-208x300.jpg 208w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine_diariogreg_12_oct-710x1024.jpg 710w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine_diariogreg_12_oct-768x1107.jpg 768w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine_diariogreg_12_oct.jpg 800w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/><\/p>\n","protected":false},"featured_media":41086,"template":"","meta":{"_tribe_modified_fields":["a:21:{s:14:\"_alp_processed\";i:1759413781;s:12:\"_EventOrigin\";i:1759413781;s:17:\"_EventShowMapLink\";i:1759413781;s:13:\"_EventShowMap\";i:1759413781;s:13:\"_EventVenueID\";i:1759413781;s:15:\"_EventStartDate\";i:1759413781;s:13:\"_EventEndDate\";i:1759413781;s:18:\"_EventStartDateUTC\";i:1759413781;s:16:\"_EventEndDateUTC\";i:1759413781;s:14:\"_EventDuration\";i:1759413781;s:14:\"_EventTimezone\";i:1759413781;s:18:\"_EventTimezoneAbbr\";i:1759413781;s:16:\"_EventRecurrence\";i:1759413781;s:21:\"_wpml_media_duplicate\";i:1759413781;s:20:\"_wpml_media_featured\";i:1759413781;s:17:\"_top_nav_excluded\";i:1759413800;s:17:\"_cms_nav_minihome\";i:1759413800;s:13:\"_thumbnail_id\";i:1759413781;s:16:\"_wpml_word_count\";i:1759413781;s:15:\"_dynamic_styles\";i:1762212733;s:20:\"_theme_options_build\";i:1769368449;}"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_thumbnail_id":["41086"],"_wpml_word_count":["40"],"_theme_options_build":["696f71999b1ad"],"event_ext":["Sala Oihanburu - Biblioteca Municipal del Valle de Eg\u00fc\u00e9s"],"event_location":["91"],"event_horario_inicio":["17:30"],"event_horario_fin":["17:30"],"event_horario":["17:30 - 17:30"],"dias":[";12-10-2025;"],"event_date":["1760290200"],"event_date1":["1760290200"]},"class_list":["post-41088","eventos","type-eventos","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Zine-Kluba. Lehen saioa: &quot;El Diario de Greg 2&quot; - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Zine-Kluba. Lehen saioa: &quot;El Diario de Greg 2&quot; - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"\u201cEl Diario de Greg 2: Carretera y manta\u201d filma proiektatuko da. 7 eta 13 urte bitarteko ikusleentzat \ud83d\uddd3\ufe0f 2025\/10\/12 \ud83d\udd5b17:30 \ud83d\udccd Oihanburu aretoa (Sarriguren) Ez da aldez aurretik izena eman behar\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-213x300.png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-lehen-saioa-el-diario-de-greg-2\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-lehen-saioa-el-diario-de-greg-2\\\/\",\"name\":\"Zine-Kluba. Lehen saioa: \\\"El Diario de Greg 2\\\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-lehen-saioa-el-diario-de-greg-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-lehen-saioa-el-diario-de-greg-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cine-club_12_oct-agenda.png\",\"datePublished\":\"2025-10-02T11:59:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-lehen-saioa-el-diario-de-greg-2\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-lehen-saioa-el-diario-de-greg-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-lehen-saioa-el-diario-de-greg-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cine-club_12_oct-agenda.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/cine-club_12_oct-agenda.png\",\"width\":800,\"height\":385},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-lehen-saioa-el-diario-de-greg-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zine-Kluba. Lehen saioa: &#8220;El Diario de Greg 2&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zine-Kluba. Lehen saioa: \"El Diario de Greg 2\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/","og_locale":"eu_ES","og_type":"article","og_title":"Zine-Kluba. Lehen saioa: \"El Diario de Greg 2\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"\u201cEl Diario de Greg 2: Carretera y manta\u201d filma proiektatuko da. 7 eta 13 urte bitarteko ikusleentzat \ud83d\uddd3\ufe0f 2025\/10\/12 \ud83d\udd5b17:30 \ud83d\udccd Oihanburu aretoa (Sarriguren) Ez da aldez aurretik izena eman behar","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","og_image":[{"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-213x300.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/","name":"Zine-Kluba. Lehen saioa: \"El Diario de Greg 2\" - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-agenda.png","datePublished":"2025-10-02T11:59:39+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-agenda.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2025\/10\/cine-club_12_oct-agenda.png","width":800,"height":385},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-lehen-saioa-el-diario-de-greg-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"Zine-Kluba. Lehen saioa: &#8220;El Diario de Greg 2&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/41088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/41086"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=41088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}