{"id":38265,"date":"2024-12-30T13:55:33","date_gmt":"2024-12-30T12:55:33","guid":{"rendered":"https:\/\/www.valledeegues.com\/?post_type=tribe_events&#038;p=38265"},"modified":"2024-12-30T15:00:38","modified_gmt":"2024-12-30T14:00:38","slug":"zine-kluba-etxean-bakarrik-ikurrak","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/","title":{"rendered":"ZINE-KLUBA &#8220;ETXEAN BAKARRIK&#8221; IKURRAK"},"content":{"rendered":"<p>Kevin McAllister zortzi urteko mutikoa da, familia ugariko kidea, eta ustekabean bere etxean abandonatuta geratzen da familia osoa Frantziara oporrak pasatzera joaten denean. Kevinek bere kabuz moldatzen ikasten du, baita Harry eta Marvengandik babesten ere, auzoan itxita dauden etxeetan lapurketetan ibili nahi duten bi lapurrak.<\/p>\n<p>lzen-ematea: sarrera libre edukiera bete arte.<\/p>\n","protected":false},"featured_media":37954,"template":"","meta":{"_tribe_modified_fields":["a:33:{s:12:\"_EventOrigin\";i:1735566824;s:16:\"_wpml_word_count\";i:1735566825;s:10:\"_edit_last\";i:1735566838;s:10:\"post_title\";i:1735566838;s:11:\"post_status\";i:1735566933;s:17:\"_EventShowMapLink\";i:1735570839;s:13:\"_EventShowMap\";i:1735566839;s:13:\"_EventVenueID\";i:1735566934;s:15:\"_EventStartDate\";i:1735566839;s:13:\"_EventEndDate\";i:1735566934;s:18:\"_EventStartDateUTC\";i:1735566839;s:16:\"_EventEndDateUTC\";i:1735566934;s:14:\"_EventDuration\";i:1735566934;s:14:\"_EventTimezone\";i:1735566839;s:18:\"_EventTimezoneAbbr\";i:1735566839;s:21:\"_wpml_media_duplicate\";i:1735566839;s:20:\"_wpml_media_featured\";i:1735566839;s:16:\"_EventRecurrence\";i:1735566839;s:12:\"cptr_related\";i:1735566839;s:13:\"_thumbnail_id\";i:1735570813;s:14:\"_alp_processed\";i:1735570839;s:27:\"_last_translation_edit_mode\";i:1735566934;s:12:\"post_content\";i:1735566933;s:26:\"_yoast_wpseo_content_score\";i:1735566933;s:43:\"_yoast_wpseo_estimated-reading-time-minutes\";i:1735566933;s:20:\"_EventCurrencySymbol\";i:1735566933;s:18:\"_EventCurrencyCode\";i:1735566933;s:22:\"_EventCurrencyPosition\";i:1735566933;s:10:\"_EventCost\";i:1735566933;s:9:\"_EventURL\";i:1735566933;s:37:\"_yoast_wpseo_primary_tribe_events_cat\";i:1735566934;s:15:\"_dynamic_styles\";i:1762102468;s:20:\"_theme_options_build\";i:1768923571;}"],"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"eu\":2,\"es\":2}}"],"_edit_lock":["1735567613:2"],"_edit_last":["2"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"cptr_related":["a:0:{}"],"_last_translation_edit_mode":["native-editor"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_yoast_wpseo_primary_tribe_events_cat":[""],"_theme_options_build":["696f71999b1ad"],"_thumbnail_id":["37954"],"event_ext":["Sala Oihanburu (Sarriguren)"],"event_location":["33621"],"event_horario_inicio":["16:30"],"event_horario_fin":["16:30"],"event_horario":["16:30 - 16:30"],"dias":[";2-1-2025;"],"event_date":["1735835400"],"event_date1":["1735835400"]},"class_list":["post-38265","eventos","type-eventos","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>ZINE-KLUBA &quot;ETXEAN BAKARRIK&quot; IKURRAK - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"ZINE-KLUBA &quot;ETXEAN BAKARRIK&quot; IKURRAK - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"Kevin McAllister zortzi urteko mutikoa da, familia ugariko kidea, eta ustekabean bere etxean abandonatuta geratzen da familia osoa Frantziara oporrak pasatzera joaten denean. Kevinek bere kabuz moldatzen ikasten du, baita Harry eta Marvengandik babesten ere, auzoan itxita dauden etxeetan lapurketetan ibili nahi duten bi lapurrak. lzen-ematea: sarrera libre edukiera bete arte.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-12-30T14:00:38+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/11\/navidadagenda.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"2234\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1257\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-etxean-bakarrik-ikurrak\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-etxean-bakarrik-ikurrak\\\/\",\"name\":\"ZINE-KLUBA \\\"ETXEAN BAKARRIK\\\" IKURRAK - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-etxean-bakarrik-ikurrak\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-etxean-bakarrik-ikurrak\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/navidadagenda.png\",\"datePublished\":\"2024-12-30T12:55:33+00:00\",\"dateModified\":\"2024-12-30T14:00:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-etxean-bakarrik-ikurrak\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-etxean-bakarrik-ikurrak\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-etxean-bakarrik-ikurrak\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/navidadagenda.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/navidadagenda.png\",\"width\":2234,\"height\":1257},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/zine-kluba-etxean-bakarrik-ikurrak\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZINE-KLUBA &#8220;ETXEAN BAKARRIK&#8221; IKURRAK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZINE-KLUBA \"ETXEAN BAKARRIK\" IKURRAK - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/","og_locale":"eu_ES","og_type":"article","og_title":"ZINE-KLUBA \"ETXEAN BAKARRIK\" IKURRAK - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"Kevin McAllister zortzi urteko mutikoa da, familia ugariko kidea, eta ustekabean bere etxean abandonatuta geratzen da familia osoa Frantziara oporrak pasatzera joaten denean. Kevinek bere kabuz moldatzen ikasten du, baita Harry eta Marvengandik babesten ere, auzoan itxita dauden etxeetan lapurketetan ibili nahi duten bi lapurrak. lzen-ematea: sarrera libre edukiera bete arte.","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_modified_time":"2024-12-30T14:00:38+00:00","og_image":[{"width":2234,"height":1257,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/11\/navidadagenda.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/","name":"ZINE-KLUBA \"ETXEAN BAKARRIK\" IKURRAK - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/11\/navidadagenda.png","datePublished":"2024-12-30T12:55:33+00:00","dateModified":"2024-12-30T14:00:38+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/11\/navidadagenda.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/11\/navidadagenda.png","width":2234,"height":1257},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/zine-kluba-etxean-bakarrik-ikurrak\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"ZINE-KLUBA &#8220;ETXEAN BAKARRIK&#8221; IKURRAK"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/38265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media\/37954"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=38265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}