{"id":37301,"date":"2024-10-07T10:12:12","date_gmt":"2024-10-07T08:12:12","guid":{"rendered":"https:\/\/www.valledeegues.com\/?post_type=tribe_events&#038;p=37301"},"modified":"2024-10-07T11:16:11","modified_gmt":"2024-10-07T09:16:11","slug":"programa-maskharah","status":"publish","type":"eventos","link":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/","title":{"rendered":"PROGRAMA MASKHARAH &#8211; Magia Tailerra (EUSKERA)"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-37298\" src=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2.png\" alt=\"\" width=\"3509\" height=\"3509\" srcset=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2.png 3509w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2-300x300.png 300w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2-1024x1024.png 1024w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2-150x150.png 150w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2-768x768.png 768w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2-1536x1536.png 1536w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2-2048x2048.png 2048w, https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2-60x60.png 60w\" sizes=\"auto, (max-width: 3509px) 100vw, 3509px\" \/><\/p>\n<p>IZEN-EMATEAK: Doan, Udalaren webgunearen bidez, izena emateko atalean dagoen formularioan, antzezpenaren aurreko astelehenetik ostegunera. Plaza baino eskaera gehiago egonez gero, zozketa eginen da. Plaza baieztatzeko, mezu bat bidaliko da posta elektronikora. Plaza libreak geratzen badira, jendea heldu ahala bete ahalko dira emanaldiaren egunean bertan.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_tribe_modified_fields":["a:36:{s:12:\"_EventOrigin\";i:1728295868;s:16:\"_wpml_word_count\";i:1728295869;s:10:\"_edit_last\";i:1728295932;s:16:\"tribe_events_cat\";i:1728288732;s:12:\"cptr_related\";i:1728295933;s:21:\"_wpml_media_has_media\";i:1728295933;s:16:\"_EventRecurrence\";i:1728295933;s:26:\"_yoast_wpseo_content_score\";i:1728295933;s:43:\"_yoast_wpseo_estimated-reading-time-minutes\";i:1728295933;s:10:\"post_title\";i:1728299093;s:12:\"post_content\";i:1728299093;s:11:\"post_status\";i:1728295933;s:17:\"_EventShowMapLink\";i:1728299772;s:13:\"_EventShowMap\";i:1728295934;s:15:\"_EventStartDate\";i:1728295934;s:13:\"_EventEndDate\";i:1728295934;s:18:\"_EventStartDateUTC\";i:1728295934;s:16:\"_EventEndDateUTC\";i:1728295934;s:14:\"_EventDuration\";i:1728295934;s:20:\"_EventCurrencySymbol\";i:1728295934;s:18:\"_EventCurrencyCode\";i:1728295934;s:22:\"_EventCurrencyPosition\";i:1728295934;s:10:\"_EventCost\";i:1728295934;s:9:\"_EventURL\";i:1728295934;s:14:\"_EventTimezone\";i:1728295934;s:18:\"_EventTimezoneAbbr\";i:1728295934;s:13:\"_EventVenueID\";i:1728295934;s:21:\"_wpml_media_duplicate\";i:1728295934;s:20:\"_wpml_media_featured\";i:1728295934;s:14:\"_alp_processed\";i:1728299772;s:27:\"_last_translation_edit_mode\";i:1728295935;s:37:\"_yoast_wpseo_primary_tribe_events_cat\";i:1728295935;s:15:\"_dynamic_styles\";i:1762272366;s:20:\"_theme_options_build\";i:1769081964;s:40:\"_oembed_cea615d7a3be58e90dd93d0b54b846b4\";i:1728331714;s:45:\"_oembed_time_cea615d7a3be58e90dd93d0b54b846b4\";i:1728331714;}"],"_wpml_word_count":["{\"total\":0,\"to_translate\":{\"eu\":2,\"es\":2}}"],"_edit_lock":["1728292468:2"],"_edit_last":["2"],"cptr_related":["a:0:{}"],"_wpml_media_has_media":["1"],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"_wpml_media_duplicate":["1"],"_wpml_media_featured":["1"],"_last_translation_edit_mode":["native-editor"],"_yoast_wpseo_primary_tribe_events_cat":[""],"_theme_options_build":["696f71999b1ad"],"_oembed_cea615d7a3be58e90dd93d0b54b846b4":["<iframe title=\"Mi nombre es Harvey Milk - Trailer espa\u00f1ol\" width=\"1140\" height=\"641\" src=\"https:\/\/www.youtube.com\/embed\/3uI5o8THOzg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>"],"_oembed_time_cea615d7a3be58e90dd93d0b54b846b4":["1728324514"],"event_ext":["Gimnasio Instituto"],"event_location":["37286"],"event_horario_inicio":["18:30"],"event_horario_fin":["18:30"],"event_horario":["18:30 - 18:30"],"dias":[";19-10-2024;"],"event_date":["1729362600"],"event_date1":["1729362600"]},"class_list":["post-37301","eventos","type-eventos","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>PROGRAMA MASKHARAH - Magia Tailerra (EUSKERA) - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/\" \/>\r\n<meta property=\"og:locale\" content=\"eu_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"PROGRAMA MASKHARAH - Magia Tailerra (EUSKERA) - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"og:description\" content=\"IZEN-EMATEAK: Doan, Udalaren webgunearen bidez, izena emateko atalean dagoen formularioan, antzezpenaren aurreko astelehenetik ostegunera. Plaza baino eskaera gehiago egonez gero, zozketa eginen da. Plaza baieztatzeko, mezu bat bidaliko da posta elektronikora. Plaza libreak geratzen badira, jendea heldu ahala bete ahalko dira emanaldiaren egunean bertan.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/EguesEguesibar\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-10-07T09:16:11+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2-1024x1024.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@AValledeEgues\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/programa-maskharah\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/programa-maskharah\\\/\",\"name\":\"PROGRAMA MASKHARAH - Magia Tailerra (EUSKERA) - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/programa-maskharah\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/programa-maskharah\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cartel_maskharah_2.png\",\"datePublished\":\"2024-10-07T08:12:12+00:00\",\"dateModified\":\"2024-10-07T09:16:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/programa-maskharah\\\/#breadcrumb\"},\"inLanguage\":\"eu-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/programa-maskharah\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/programa-maskharah\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cartel_maskharah_2.png\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/cartel_maskharah_2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/eventos\\\/programa-maskharah\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Azala\",\"item\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PROGRAMA MASKHARAH &#8211; Magia Tailerra (EUSKERA)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#website\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"name\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"description\":\"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"eu-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#organization\",\"name\":\"Ayuntamiento Valle de Egues\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"eu-ES\",\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"contentUrl\":\"https:\\\/\\\/www.valledeegues.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/logo-egues-escudo.svg\",\"width\":529,\"height\":125,\"caption\":\"Ayuntamiento Valle de Egues\"},\"image\":{\"@id\":\"https:\\\/\\\/www.valledeegues.com\\\/eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/EguesEguesibar\",\"https:\\\/\\\/x.com\\\/AValledeEgues\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCUPvmkTy56ZAhGTVrzg4uDQ\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PROGRAMA MASKHARAH - Magia Tailerra (EUSKERA) - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/","og_locale":"eu_ES","og_type":"article","og_title":"PROGRAMA MASKHARAH - Magia Tailerra (EUSKERA) - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","og_description":"IZEN-EMATEAK: Doan, Udalaren webgunearen bidez, izena emateko atalean dagoen formularioan, antzezpenaren aurreko astelehenetik ostegunera. Plaza baino eskaera gehiago egonez gero, zozketa eginen da. Plaza baieztatzeko, mezu bat bidaliko da posta elektronikora. Plaza libreak geratzen badira, jendea heldu ahala bete ahalko dira emanaldiaren egunean bertan.","og_url":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/","og_site_name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","article_publisher":"https:\/\/www.facebook.com\/EguesEguesibar","article_modified_time":"2024-10-07T09:16:11+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2-1024x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@AValledeEgues","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/","url":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/","name":"PROGRAMA MASKHARAH - Magia Tailerra (EUSKERA) - Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","isPartOf":{"@id":"https:\/\/www.valledeegues.com\/eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/#primaryimage"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/#primaryimage"},"thumbnailUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2.png","datePublished":"2024-10-07T08:12:12+00:00","dateModified":"2024-10-07T09:16:11+00:00","breadcrumb":{"@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/#breadcrumb"},"inLanguage":"eu-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/"]}]},{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/#primaryimage","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2.png","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2024\/10\/cartel_maskharah_2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.valledeegues.com\/eu\/eventos\/programa-maskharah\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Azala","item":"https:\/\/www.valledeegues.com\/eu\/"},{"@type":"ListItem","position":2,"name":"PROGRAMA MASKHARAH &#8211; Magia Tailerra (EUSKERA)"}]},{"@type":"WebSite","@id":"https:\/\/www.valledeegues.com\/eu\/#website","url":"https:\/\/www.valledeegues.com\/eu\/","name":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","description":"Ayuntamiento Valle de Eg\u00fc\u00e9s | Eguesibarko Udala","publisher":{"@id":"https:\/\/www.valledeegues.com\/eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.valledeegues.com\/eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"eu-ES"},{"@type":"Organization","@id":"https:\/\/www.valledeegues.com\/eu\/#organization","name":"Ayuntamiento Valle de Egues","url":"https:\/\/www.valledeegues.com\/eu\/","logo":{"@type":"ImageObject","inLanguage":"eu-ES","@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/","url":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","contentUrl":"https:\/\/www.valledeegues.com\/wp-content\/uploads\/2019\/06\/logo-egues-escudo.svg","width":529,"height":125,"caption":"Ayuntamiento Valle de Egues"},"image":{"@id":"https:\/\/www.valledeegues.com\/eu\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/EguesEguesibar","https:\/\/x.com\/AValledeEgues","https:\/\/www.youtube.com\/channel\/UCUPvmkTy56ZAhGTVrzg4uDQ"]}]}},"_links":{"self":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos\/37301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/eventos"}],"about":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/types\/eventos"}],"wp:attachment":[{"href":"https:\/\/www.valledeegues.com\/eu\/wp-json\/wp\/v2\/media?parent=37301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}